{"id":33655,"date":"2025-05-05T14:30:41","date_gmt":"2025-05-05T17:30:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=33655"},"modified":"2025-05-05T14:30:41","modified_gmt":"2025-05-05T17:30:41","slug":"de-olho-na-lingua-120","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-120\/","title":{"rendered":"De Olho na L\u00edngua"},"content":{"rendered":"<p>Minha opini\u00e3o \u201cpessoal\u201d<br \/>\nFrase comu m e corriqueira na imprensa e at\u00e9 usada por pessoas formadas. Mas \u00e9 vis\u00edvel a redund\u00e2ncia. Ora, se a opini\u00e3o \u00e9 minha, s\u00f3 pode ser pessoal.<\/p>\n<p>Dolo (Como se pronuncia?)<br \/>\n\u00c9 aberto o timbre da vogal t\u00f4nica dessa palavra: D\u00d3LO. Com a conclus\u00e3o do inqu\u00e9rito sobre o acidente com o avi\u00e3o da TA, tanto os parentes das v\u00edtimas como seus advogados falavam em \u201cdolo\u201d. Mas, afinal, o que seria \u201cd\u00f4lo\u201d? N\u00e3o tenho a menor ideia. Mas dolo (\u2018d\u00f3\u2019) significa enganoso, falso, m\u00e1 f\u00e9, hip\u00f3crita, preconcebido.<\/p>\n<p>V\u00edrgula antes de etc.<br \/>\n\u00c9 opcional. Pela l\u00f3gica, n\u00e3o. Etc. \u00e9 a abreviatura de uma express\u00e3o latina que come\u00e7a pelo e (\u00e9): Et cetera (Et coetera). Significa \u201ce outras coisas\u201d. Ora, em geral, n\u00e3o se v\u00edrgula antes do e (\u00e9). Consequentemente, tamb\u00e9m n\u00e3o se usa a v\u00edrgula antes do etc.<br \/>\n\u00c9 correto, portanto, escrever assim, por exemplo: Curso para noivos implica cidad\u00e3os cat\u00f3licos, batismo, primeira comunh\u00e3o, pagamento da taxa etc. Pela tradi\u00e7\u00e3o, sim. Mas a tradi\u00e7\u00e3o j\u00e1 consagrou o uso dessa v\u00edrgula. At\u00e9 o Vocabul\u00e1rio Ortogr\u00e1fico da L\u00edngua Portuguesa (VOLP) faz isso. Tamb\u00e9m \u00e9 correto, portanto, escrever assim: O curso para noivos implica candidatos cat\u00f3licos, batismo, primeira comunh\u00e3o, pagamento da taxa, etc.<\/p>\n<p>Etc. s\u00f3 se aplica a coisa?<br \/>\nDeveria. Mas, com o tempo, tamb\u00e9m passou a aplicar-se a pessoas e a animais. Ex.: Ali ficamos todos: alunos, professores, diretor, funcion\u00e1rios, livros, c\u00e3o da escola, etc.<\/p>\n<p>O c\u00f4njuge ou a c\u00f4njuge?<br \/>\nSempre o c\u00f4njuge. A palavra c\u00f4njuge, seja homem ou seja mulher, \u00e9 sempre masculina. E como \u00e9 que se vai saber quando nos referimos a ele ou a ela?<br \/>\nA\u00ed, se usam, por exemplo, os termos homem e mulher, posteriormente. Ex.: O c\u00f4njuge homem (ou do sexo masculino), o c\u00f4njuge mulher (ou do sexo feminino).<\/p>\n<p>O mascote ou a mascote?<br \/>\nUse sempre a mascote. &#8211; Mesmo sendo um menino?! &#8211; Sim. A palavra mascote (ser humano, animal ou coisa a que se atribui o dom de dar sorte a uma pessoa, a uma sociedade desportiva, a uma institui\u00e7\u00e3o ou a um grupo) \u00e9 sempre feminina. Veio do franc\u00eas \u201cmascotte\u201d no feminino e mant\u00e9m esse g\u00eanero no Portugu\u00eas. Ex.: Maria \u00e9 a nossa mascote; Carlos \u00e9 a mascote do nosso time; O urubu \u00e9 a mascote do Flamengo.<\/p>\n<p>Um aforismo ou Um aforisma?<br \/>\nPor\u00e9m \u201caforismo\u201d (= Senten\u00e7a, m\u00e1xima, proposi\u00e7\u00e3o) \u00e9 tamb\u00e9m palavra grega e termina por \u201cmo\u201d (com o) \u00e9 do g\u00eanero masculino. Ex.: \u201cAmai vossos inimigos\u201d \u00e9 um dos mais c\u00e9lebres aforismos da doutrina crist\u00e3. Outra palavra que muita gente claudica ao escrever \u00e9 cataclismo. Significa inunda\u00e7\u00e3o, transforma\u00e7\u00e3o ecol\u00f3gica, desastre social, derrocada, cat\u00e1strofe. Esta palavra \u00e9 tamb\u00e9m do g\u00eanero masculino. Diga-se: Um cataclismo, o cataclismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minha opini\u00e3o \u201cpessoal\u201d Frase comu m e corriqueira na imprensa e at\u00e9 usada por pessoas&#8230;<\/p>\n","protected":false},"author":7,"featured_media":17923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,12],"tags":[],"class_list":["post-33655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-de-olho-na-lingua"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/\" rel=\"category tag\">De olho na l\u00edngua<\/a>","tag_info":"De olho na l\u00edngua","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg","jetpack-related-posts":[{"id":24511,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-51\/","url_meta":{"origin":33655,"position":0},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"De Olho na L\u00edngua Prof. Ant\u00f4nio da Costa Reverter o quadro A frase em ep\u00edgrafe est\u00e1 na moda. M\u00e9dicos, economistas, tecnocratas de todas as \u00e1reas e principalmente cronistas esportivos est\u00e3o a inventar uma l\u00edngua pr\u00f3pria: A asinina. Entre tantas asnices que se notam em linguagem desses profissionais, salienta-se o emprego\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":38871,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-161\/","url_meta":{"origin":33655,"position":1},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Junho 28, 2026","format":false,"excerpt":"\u201cM\u00e1rcio namora Daniela\u201d ou \u201cM\u00e1rcio namora com Daniela\u201d? A primeira. O verbo namorar \u00e9 transitivo direto em Portugu\u00eas; em italiano, sim, \u00e9 transitivo indireto, mas n\u00f3s falamos portugu\u00eas. Ex.: Aguinaldo namora Rita desde 1995; Jamais namoraria uma garota dessas. A preposi\u00e7\u00e3o \u201ccom\u201d talvez seja usada, tamb\u00e9m, por influ\u00eancia da reg\u00eancia\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":19149,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-49\/","url_meta":{"origin":33655,"position":2},"title":"De Olho na L\u00edngua","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"Cliente ou fregu\u00eas (Qual a diferen\u00e7a?) Cliente \u00e9 a pessoa que utiliza os servi\u00e7os de um profissional liberal. Fregu\u00eas \u00e9 aquele que frequentemente compra coisas numa mesma loja, num mesmo armaz\u00e9m, num mesmo supermercado, etc. ou aquele que costuma ir sempre ao mesmo bar, restaurante, etc. A palavra \u00e9 estrita\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32582,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-116\/","url_meta":{"origin":33655,"position":3},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Fevereiro 18, 2025","format":false,"excerpt":"Caso hajam (ou haja?) problemas, chamaremos o diretor. A constru\u00e7\u00e3o correta \u00e9: Caso haja problemas, chamaremos o diretor. O verbo haver, quando empregado na acep\u00e7\u00e3o de existir, ocorrer ou acontecer, \u00e9 impessoal, n\u00e3o admite flex\u00e3o. Exs.: Ci\u00fames havia na rela\u00e7\u00e3o deles; Diverg\u00eancias jamais haver\u00e1 entre n\u00f3s; Costuma haver situa\u00e7\u00f5es delicadas;\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":39290,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-165\/","url_meta":{"origin":33655,"position":4},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Julho 14, 2026","format":false,"excerpt":"\u201cO \u00c1guia de Haia\u201d ou \u201cA \u00c1guia de Haia\u201d? Deve-se dizer: A \u00c1guia de Haia. Ep\u00edteto recebido por Rui Barbosa, por sua brilhante atua\u00e7\u00e3o na Confer\u00eancia Internacional de Paz de Haia, Holanda, em 1907, demonstrando vasto conhecimento de leis. Foi cunhado pelo Bar\u00e3o do Rio Branco. Rui (que muitos preferem\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17922,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-36\/","url_meta":{"origin":33655,"position":5},"title":"De Olho na L\u00edngua","author":"","date":"Novembro 7, 2021","format":false,"excerpt":"Ir e Vir H\u00e1 quem confunda a conjuga\u00e7\u00e3o destes dois verbos, no presente do indicativo de ser assim:\u00a0IR: Vou, vais, vai, vamos, ides, v\u00e3o.\u00a0VIR: Venho, vens, vem, vimos, vindes, v\u00eam. \u00c9 bom estar atento para evitar erro comum, quanto ao emprego de VIR, na primeira pessoa do indicativo presente. Quando\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33655"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33655\/revisions"}],"predecessor-version":[{"id":33656,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33655\/revisions\/33656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17923"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=33655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=33655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=33655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}