{"id":33657,"date":"2025-05-05T14:32:42","date_gmt":"2025-05-05T17:32:42","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=33657"},"modified":"2025-05-05T14:32:42","modified_gmt":"2025-05-05T17:32:42","slug":"prefeito-oscar-rodrigues-recebe-comitiva-do-ministerio-da-saude-para-dialogar-solucoes-para-a-santa-casa-de-sobral","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/prefeito-oscar-rodrigues-recebe-comitiva-do-ministerio-da-saude-para-dialogar-solucoes-para-a-santa-casa-de-sobral\/","title":{"rendered":"Prefeito Oscar Rodrigues recebe comitiva do Minist\u00e9rio da Sa\u00fade para dialogar solu\u00e7\u00f5es para a Santa Casa de Sobral"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-33657 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/prefeito-oscar-rodrigues-recebe-comitiva-do-ministerio-da-saude-para-dialogar-solucoes-para-a-santa-casa-de-sobral\/1ok-santa-casa\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"1ok SANTA CASA\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/prefeito-oscar-rodrigues-recebe-comitiva-do-ministerio-da-saude-para-dialogar-solucoes-para-a-santa-casa-de-sobral\/3ok-santa-casa\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/3ok-SANTA-CASA-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"3ok SANTA CASA\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Sobral recebeu nesta sexta-feira, 2 de maio, uma comitiva do Minist\u00e9rio da Sa\u00fade e da Secretaria de Sa\u00fade do Estado, recepcionada pelo prefeito de Sobral, Oscar Rodrigues. O objetivo \u00e9 encontrar solu\u00e7\u00f5es para a crise enfrentada pela Santa Casa de Miseric\u00f3rdia de Sobral, um cen\u00e1rio deixado pela gest\u00e3o anterior. Foram dialogadas alternativas de custeio e melhoria do parque de imagem e tecnol\u00f3gico do hospital com um compartilhamento de responsabilidades entre Minist\u00e9rio da Sa\u00fade, Secretaria de Sa\u00fade do Estado e munic\u00edpios.<br \/>\nA vice-prefeita Dra. Imaculada Dias Adeodato, \u00a0e a Primeira-dama, a Secret\u00e1ria dos Direitos Humanos e da Assist\u00eancia Social, Dra. Vanessa Braga e a Secret\u00e1ria de Sa\u00fade de Sobral, Michelle Alves tamb\u00e9m recepcionaram a comitiva. Vieram a Sobral o Secret\u00e1rio de Aten\u00e7\u00e3o Especializada do Minist\u00e9rio da Sa\u00fade, Dr. Mozart Sales e a Secret\u00e1ria de Sa\u00fade do Estado, Dra. T\u00e2nia Mara Coelho. Tamb\u00e9m participaram o Deputado Federal Moses Rodrigues, a Superintendente de Sa\u00fade da Regi\u00e3o Norte, M\u00f4nica Lima, e o presidente da C\u00e2mara Municipal de Sobral, Chico Joia J\u00fanior, al\u00e9m dos secret\u00e1rios municipais Hermenegildo Sousa Neto (Infraestrutura) e Soraya S\u00e1 (Finan\u00e7as) e dos vereadores Sidcley J\u00fanior e Fransquinha do Povo.<br \/>\nOs diretores da Santa Casa Jos\u00e9 Ueides Fechine J\u00fanior (Diretor-Geral) e Lizandro de Andrade Teles (Diretor T\u00e9cnico) apresentaram os desafios da unidade de sa\u00fade. O hospital conta com 382 leitos e atende uma popula\u00e7\u00e3o de aproximadamente 1,6 milh\u00e3o de habitantes em 55 munic\u00edpios.<br \/>\nAs articula\u00e7\u00f5es sobre a Santa Casa foram iniciadas em Bras\u00edlia, em reuni\u00e3o ocorrida no dia 8 de abril, no Minist\u00e9rio da Sa\u00fade. O compromisso conjunto dos governos Municipal, Estadual e Federal segue firme na constru\u00e7\u00e3o de alternativas que assegurem o funcionamento pleno da Santa Casa e a continuidade dos servi\u00e7os essenciais prestados \u00e0 popula\u00e7\u00e3o de Sobral e de toda a Regi\u00e3o Norte do Cear\u00e1.<br \/>\nFonte: Comunica\u00e7\u00e3o da Prefeitura de Sobral<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobral recebeu nesta sexta-feira, 2 de maio, uma comitiva do Minist\u00e9rio da Sa\u00fade e da&#8230;<\/p>\n","protected":false},"author":7,"featured_media":33658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-33657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg",2560,1706,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-300x200.jpg",300,200,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-768x512.jpg",640,427,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-2048x1365.jpg",2048,1365,true],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-1024x683.jpg",1024,683,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-540x340.jpg",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg","jetpack-related-posts":[{"id":35266,"url":"https:\/\/correiodasemana.com\/site\/o-prefeito-oscar-rodrigues-e-o-deputado-federal-moses-rodrigues-articulam-conquista-de-r175-milhoes-para-a-santa-casa-de-sobral\/","url_meta":{"origin":33657,"position":0},"title":"O prefeito Oscar Rodrigues e o deputado federal Moses Rodrigues articulam conquista de R$17,5 milh\u00f5es para a Santa Casa de Sobral","author":"adminredacao","date":"Agosto 25, 2025","format":false,"excerpt":"O trabalho conjunto entre o prefeito de Sobral, Oscar Rodrigues, e o deputado federal Moses Rodrigues junto ao Governo Federal resultou em um importante conquista para a sa\u00fade p\u00fablica de toda a regi\u00e3o Norte do Cear\u00e1. O Minist\u00e9rio da Sa\u00fade publicou no Di\u00e1rio Oficial da Uni\u00e3o desta quinta-feira (21\/08) a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/oscar-e-moses-rodrigues.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/oscar-e-moses-rodrigues.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/oscar-e-moses-rodrigues.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/oscar-e-moses-rodrigues.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33314,"url":"https:\/\/correiodasemana.com\/site\/prefeitura-de-sobral-articula-apoio-do-ministerio-da-saude-para-solucionar-a-critica-situacao-da-santa-casa-de-misericordia-de-sobral-deixada-pela-gestao-passada\/","url_meta":{"origin":33657,"position":1},"title":"Prefeitura de Sobral articula apoio do Minist\u00e9rio da Sa\u00fade para solucionar a cr\u00edtica situa\u00e7\u00e3o da Santa Casa de Miseric\u00f3rdia de Sobral deixada pela gest\u00e3o passada","author":"adminredacao","date":"Abril 14, 2025","format":false,"excerpt":"Nesta ter\u00e7a-feira (08 de abril), aconteceu uma importante reuni\u00e3o em Bras\u00edlia, no Minist\u00e9rio da Sa\u00fade, com o objetivo de encontrar solu\u00e7\u00f5es efetivas e sustent\u00e1veis para a Santa Casa de Miseric\u00f3rdia de Sobral, hospital de refer\u00eancia na Zona Norte do Estado do Cear\u00e1. As autoridades abordaram a necessidade de implementar a\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Reuniao-Brasilia.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Reuniao-Brasilia.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Reuniao-Brasilia.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Reuniao-Brasilia.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34531,"url":"https:\/\/correiodasemana.com\/site\/o-primeiro-centro-de-especialidades-odontologicas-ceo-do-brasil-sera-reaberto\/","url_meta":{"origin":33657,"position":2},"title":"O primeiro Centro de Especialidades Odontol\u00f3gicas (CEO) do Brasil, ser\u00e1 reaberto","author":"adminredacao","date":"Julho 8, 2025","format":false,"excerpt":"A Prefeitura de Sobral, por meio da Secretaria da Sa\u00fade, em parceria com o Governo do Estado e o Minist\u00e9rio da Sa\u00fade, recebeu na segunda-feira, (01\/07) o Coordenador-Geral de Sa\u00fade Bucal do Minist\u00e9rio da Sa\u00fade, Dr. \u00c9dson Lucena, e o Coordenador de Sa\u00fade Bucal do Estado do Cear\u00e1, Dr. Nalber\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/A-Prefeitura-de-Sobral-por-meio-da-Secretaria-da-Saude-em-parceria-com-o-Governo-do-Estado-e-o-Ministerio-da-Saude-recebeu-nesta-segunda-feira-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/A-Prefeitura-de-Sobral-por-meio-da-Secretaria-da-Saude-em-parceria-com-o-Governo-do-Estado-e-o-Ministerio-da-Saude-recebeu-nesta-segunda-feira-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/A-Prefeitura-de-Sobral-por-meio-da-Secretaria-da-Saude-em-parceria-com-o-Governo-do-Estado-e-o-Ministerio-da-Saude-recebeu-nesta-segunda-feira-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/A-Prefeitura-de-Sobral-por-meio-da-Secretaria-da-Saude-em-parceria-com-o-Governo-do-Estado-e-o-Ministerio-da-Saude-recebeu-nesta-segunda-feira-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/A-Prefeitura-de-Sobral-por-meio-da-Secretaria-da-Saude-em-parceria-com-o-Governo-do-Estado-e-o-Ministerio-da-Saude-recebeu-nesta-segunda-feira-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35373,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-e-o-primeiro-hospital-filantropico-do-ceara-a-aderir-ao-programa-agora-tem-especialistas\/","url_meta":{"origin":33657,"position":3},"title":"Santa Casa de Sobral \u00e9 o primeiro hospital filantr\u00f3pico do Cear\u00e1 a aderir ao programa Agora Tem Especialistas","author":"adminredacao","date":"Setembro 1, 2025","format":false,"excerpt":"O Minist\u00e9rio da Sa\u00fade anunciou a ades\u00e3o da Santa Casa de Miseric\u00f3rdia de Sobral ao programa Agora Tem Especialistas. A institui\u00e7\u00e3o \u00e9 o primeiro hospital filantr\u00f3pico do Cear\u00e1 a aderir \u00e0 iniciativa do Governo Federal e est\u00e1 entre os tr\u00eas primeiros hospitais privados e filantr\u00f3picos a aderirem a esta modalidade\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Agora-tem-especialistas-3-scaled.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":32485,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-e-prefeitura-de-sobral-discutem-avancos-para-o-hospital-durante-reuniao\/","url_meta":{"origin":33657,"position":4},"title":"Santa Casa e Prefeitura de Sobral discutem avan\u00e7os para o hospital durante reuni\u00e3o","author":"adminredacao","date":"Fevereiro 10, 2025","format":false,"excerpt":"Na quarta-feira (05\/02), os diretores da Santa Casa de Miseric\u00f3rdia de Sobral participaram de uma reuni\u00e3o no gabinete do prefeito de Sobral, Oscar Rodrigues, para discutir quest\u00f5es relacionadas \u00e0 gest\u00e3o do hospital, que segue sob interven\u00e7\u00e3o da prefeitura desde 2022. Na ocasi\u00e3o, foram apresentados dados sobre o funcionamento da Santa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/476163071_952922720303155_2285069911277909879_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/476163071_952922720303155_2285069911277909879_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/476163071_952922720303155_2285069911277909879_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/476163071_952922720303155_2285069911277909879_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34846,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-retoma-gestao-pela-diocese-sob-nova-direcao\/","url_meta":{"origin":33657,"position":5},"title":"Santa Casa de Sobral retoma gest\u00e3o pela Diocese sob nova dire\u00e7\u00e3o","author":"adminredacao","date":"Julho 28, 2025","format":false,"excerpt":"A Associa\u00e7\u00e3o Santa Casa de Miseric\u00f3rdia de Sobral (ASCMS) informa que foi oficialmente revogado o decreto de interven\u00e7\u00e3o municipal que vigorava sobre o hospital Santa Casa de Miseric\u00f3rdia de Sobral. Com o fim da interven\u00e7\u00e3o municipal, o hospital retorna \u00e0 gest\u00e3o da sua associa\u00e7\u00e3o mantenedora. A decis\u00e3o resulta de um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33657"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33657\/revisions"}],"predecessor-version":[{"id":33660,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33657\/revisions\/33660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/33658"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=33657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=33657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=33657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}