{"id":33783,"date":"2025-05-19T10:30:06","date_gmt":"2025-05-19T13:30:06","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=33783"},"modified":"2025-05-19T10:30:06","modified_gmt":"2025-05-19T13:30:06","slug":"em-tempo-277","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-277\/","title":{"rendered":"EM TEMPO \u2022"},"content":{"rendered":"<p>S\u00e9rie cearense \u201cSe Avexe N\u00e3o\u201d na Netflix<br \/>\nAp\u00f3s exibi\u00e7\u00e3o na TV Brasil e pr\u00e9-estreia em 2024 em Fortaleza, a s\u00e9rie cearense \u201cSe Avexe N\u00e3o\u201d foi exibida em novas telas em todo o Pa\u00eds. No dia 9 de maio, a produ\u00e7\u00e3o teve estreia na Netflix Brasil, mais um passo importante para divulga\u00e7\u00e3o do audiovisual do Estado.<br \/>\nA s\u00e9rie foi viabilizada atrav\u00e9s de um edital do Programa de Apoio ao Desenvolvimento do Audiovisual Brasileiro. O elenco, 100% cearense, \u00e9 formado por Juliana Maia, Fab\u00edola L\u00edper, Rafael Martins, Bruna Pessoa, Lucas Cavalcante, Luiza Rios, Mateus Franklin e Bilica Leo.<\/p>\n<p>Rede de Escolas Livres de Arte e Cultura<br \/>\nUniversidade Federal do Cear\u00e1, em parceria com o Minist\u00e9rio da Cultura, realiza, de 26 a 30 de maio, em Fortaleza, o Encontro da Rede Nacional de Escolas Livres de Arte e Cultura, com presen\u00e7a de gestores p\u00fablicos e pesquisadores, al\u00e9m de 68 organiza\u00e7\u00f5es da sociedade civil.<br \/>\nA solenidade de abertura, dia 26, \u00e0s 18h, ser\u00e1 no audit\u00f3rio da Reitoria da UFC. Com o intuito de fomentar a transmiss\u00e3o de saberes e as pedagogias de forma\u00e7\u00e3o em arte e cultura, o evento ter\u00e1 cinco dias de interc\u00e2mbio criativo, oficinas, plen\u00e1rias, debates e grupos de trabalho.<\/p>\n<p>Produ\u00e7\u00f5es exclusivas de discos de vinil<\/p>\n<div id='gallery-1' class='gallery galleryid-33783 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/em-tempo-277\/discos-de-vinil-davi-rocha-6\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/discos-de-vinil-davi-rocha-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"discos-de-vinil-davi-rocha (6)\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Edimar Lima, fundador da Wakati Produ\u00e7\u00f5es, com discos produzidos pelo selo<br \/>\nA empresa cearense Wakati Produ\u00e7\u00f5es, idealizada por Edimar Lima, hoje faz parte da lista seleta de selos de vinil no Nordeste. Primeiro vinil foi edi\u00e7\u00e3o especial do disco \u201cAgridoce\u201d (2011), hom\u00f4nimo do projeto paralelo da cantora Pitty e do guitarrista Martin Mendezz.<br \/>\nAp\u00f3s a estreia, a Wakati colocou no mercado edi\u00e7\u00f5es exclusivas de vinil, com destaque para \u201cPercorrer em N\u00f3s\u201d, do duo \u00c0VU\u00c0, Bruna Black e Jottap\u00ea; \u201cAfeto e luta: Bruna Caram canta Gonzaguinha\u201d. O lan\u00e7amento mais recente \u00e9 do disco \u201cAmar\u00edssima\u201d, da baiana Melly.<\/p>\n<p>Divulgada carta in\u00e9dita de Rita Lee<br \/>\nA fam\u00edlia de Rita Lee divulgou uma carta in\u00e9dita escrita pela cantora pouco antes de sua morte, que completou dois anos no dia 10 de maio. Registro foi revelado no document\u00e1rio \u201cRita Lee: Mania de Voc\u00ea\u201d, dispon\u00edvel na plataforma Max (https:\/\/pipocamoderna.com.br).<br \/>\nConte\u00fado da mensagem foi lido em voz alta por Beto Lee e Roberto de Carvalho, vi\u00favo da artista. Na carta, Rita Lee declarou seu amor e gratid\u00e3o \u00e0 fam\u00edlia, com uma homenagem especial ao marido. Tamb\u00e9m deixou palavras carinhosas para os filhos Beto, Jo\u00e3o e Ant\u00f4nio.<\/p>\n<p>Congresso de engenharia civil na UnB<br \/>\nO Distrito Federal ser\u00e1 palco, de 16 a 18 de junho, do XXI Congresso Internacional sobre Patologia de Edif\u00edcios e Repara\u00e7\u00e3o de Constru\u00e7\u00f5es (CINPAR). Edi\u00e7\u00e3o deste ano ser\u00e1 na Universidade de Bras\u00edlia (UnB), fortalecendo a pesquisa brasileira no cen\u00e1rio internacional.<br \/>\nSer\u00e3o abordados temas como sustentabilidade, materiais inovadores, reabilita\u00e7\u00e3o do patrim\u00f4nio edificado e efici\u00eancia energ\u00e9tica. Reconhecido mundialmente, o CINPAR j\u00e1 passou por seis pa\u00edses. Foi criado em 2003, em Sobral, na Universidade Estadual Vale do Acara\u00fa.<\/p>\n<p>Dica da Coluna<br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br): Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e9rie cearense \u201cSe Avexe N\u00e3o\u201d na Netflix Ap\u00f3s exibi\u00e7\u00e3o na TV Brasil e pr\u00e9-estreia em&#8230;<\/p>\n","protected":false},"author":7,"featured_media":18025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,36],"tags":[],"class_list":["post-33783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva-300x271.jpg",300,271,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg",315,285,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/em-tempo\/\" rel=\"category tag\">Em Tempo<\/a>","tag_info":"Em Tempo","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg","jetpack-related-posts":[{"id":18179,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-110\/","url_meta":{"origin":33783,"position":0},"title":"Em Tempo","author":"","date":"Novembro 28, 2021","format":false,"excerpt":"Editais de incentivo \u00e0s artes e ao cinema O governador\u00a0Camilo Santana\u00a0anunciou com\u00a0Fabiano\u00a0Pi\u00faba,\u00a0secret\u00e1rio da Cultura do Cear\u00e1, o lan\u00e7amento de dois editais culturais em dezembro: Incentivo \u00e0s Artes e ao Cinema e V\u00eddeo. A informa\u00e7\u00e3o foi revelada durante uma live nas redes sociais, no dia 23 de novembro. Atores, diretores e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/CNBB-PREMIO_n-300x199.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":24657,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-175\/","url_meta":{"origin":33783,"position":1},"title":"Em Tempo","author":"adminredacao","date":"Maio 14, 2023","format":false,"excerpt":"Sobral sediar\u00e1 congresso internacional Nos dias 8,9 e 10 de junho acontecer\u00e1 em Sobral o XIX Congresso Internacional sobre Patologia e Reabilita\u00e7\u00e3o das Constru\u00e7\u00f5es (Cinpar 2023). O presidente do comit\u00ea executivo \u00e9 o professor Francisco Carvalho, vice-reitor da Universidade Estadual Vale do Acara\u00fa (UVA). O Cinpar surgiu em 2003, com\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/ok-rita_6--300x179.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19619,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-130\/","url_meta":{"origin":33783,"position":2},"title":"Em Tempo","author":"","date":"Abril 24, 2022","format":false,"excerpt":"Pr\u00eamio Sesc de Artes C\u00eanicas O Pr\u00eamio Sesc de Artes C\u00eanicas recebe propostas de espet\u00e1culos at\u00e9 o dia 8 de maio, com inscri\u00e7\u00f5es de projetos in\u00e9ditos de teatro, dan\u00e7a, circo e outras modalidades. Cinco propostas ser\u00e3o contempladas: uma receber\u00e1 R$100 mil, duas ganhar\u00e3o R$70 mil e outras duas ter\u00e3o R$50\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/cantor-fortaleza-300x275.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":34088,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-280\/","url_meta":{"origin":33783,"position":3},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Junho 9, 2025","format":false,"excerpt":"2\u00aa edi\u00e7\u00e3o do Pr\u00eamio UFC de Jornalismo A Universidade Federal do Cear\u00e1 lan\u00e7ou o edital da segunda edi\u00e7\u00e3o do Pr\u00eamio UFC de Jornalismo. As inscri\u00e7\u00f5es ficam abertas at\u00e9 21 de setembro, por meio de formul\u00e1rio online. A divulga\u00e7\u00e3o dos trabalhos finalistas ser\u00e1 dia 30 de outubro; e a premia\u00e7\u00e3o em\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/BACELAR-Foto-Iara-Pereira-02-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/BACELAR-Foto-Iara-Pereira-02-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/BACELAR-Foto-Iara-Pereira-02-150x150.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":33547,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-274\/","url_meta":{"origin":33783,"position":4},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 29, 2025","format":false,"excerpt":"Vestibular da UVA com notas do Enem A Universidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es at\u00e9 o dia 6 de maio para Vestibular 2025.2, com aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem). Ser\u00e3o aceitas as pontua\u00e7\u00f5es das dez \u00faltimas edi\u00e7\u00f5es, realizadas entre 2015 e 2024. S\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28779,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-220\/","url_meta":{"origin":33783,"position":5},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Mar\u00e7o 25, 2024","format":false,"excerpt":"Homenagem ao artista Belchior Vai \u00e0 san\u00e7\u00e3o presidencial projeto de lei do deputado federal Le\u00f4nidas Cristino, que denomina Ant\u00f4nio Carlos Belchior o Terminal Mar\u00edtimo de Passageiros do Porto de Fortaleza, no Mucuripe. Belchior morreu em 2017, aos 70 anos, mas suas m\u00fasicas fazem sucesso at\u00e9 hoje. O projeto, aprovado no\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33783"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33783\/revisions"}],"predecessor-version":[{"id":33785,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33783\/revisions\/33785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18025"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=33783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=33783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=33783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}