{"id":35165,"date":"2025-08-17T21:58:44","date_gmt":"2025-08-18T00:58:44","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=35165"},"modified":"2025-08-17T21:58:44","modified_gmt":"2025-08-18T00:58:44","slug":"jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/","title":{"rendered":"Jord\u00e3o abre Festa de Nossa Senhora da Sa\u00fade 2025 com f\u00e9, m\u00fasica e miss\u00e3o"},"content":{"rendered":"<p>Na manh\u00e3 desta quinta-feira, 14 de agosto, a comunidade de Jord\u00e3o deu in\u00edcio \u00e0 tradicional Festa de Nossa Senhora da Sa\u00fade 2025, reunindo f\u00e9, cultura e devo\u00e7\u00e3o. O dia come\u00e7ou \u00e0s 6h com o repicar festivo do sino da Igreja Matriz e de todas as capelas, anunciando o in\u00edcio dos festejos. Logo em seguida, fi\u00e9is se reuniram na nova pra\u00e7a do distrito para a partilha do caf\u00e9, momento que contou com a b\u00ean\u00e7\u00e3o dos presentes e dos transportes.<br \/>\n\u00c0s 8h, foi celebrada a Santa Missa em A\u00e7\u00e3o de Gra\u00e7as por todos os mission\u00e1rios e volunt\u00e1rios que assumir\u00e3o as equipes de trabalho ao longo da festa. Em seguida, ocorreu o hasteamento das bandeiras da Diocese de Sobral, da \u00c1rea Pastoral e da padroeira, ato que marcou oficialmente a abertura dos festejos deste ano.<br \/>\n\u00c0 noite, a programa\u00e7\u00e3o seguiu com a chegada da Banda de M\u00fasica Maestro Francisco Ara\u00fajo, da cidade de Marco, sob a reg\u00eancia do Maestro Iranir Bandeira. O grupo percorreu as ruas de Jord\u00e3o levando m\u00fasica e alegria, e depois encantou o p\u00fablico com uma apresenta\u00e7\u00e3o no palco, mesclando repert\u00f3rio variado e destacando can\u00e7\u00f5es marianas e do Sagrado Cora\u00e7\u00e3o de Jesus. A banda de m\u00fasica foi recepcionada na ETI Dr Jos\u00e9 Euclides, conduzidos pelos membros da Comunidade Rainha da Paz Miss\u00e3o Jord\u00e3o. J\u00e1 no palco da festa, Padre Assis acolheu os presentes e os visitantes, sendo acompanhado do Vereador Jonhson que proferiu suas palavras em nome da gest\u00e3o municipal.<br \/>\nA noite tamb\u00e9m reservou um momento especial de mem\u00f3ria e espiritualidade com a apresenta\u00e7\u00e3o sobre o Servo de Deus Monsenhor Waldir, conduzida pelo Maestro Iranir e do Vener\u00e1vel Padre Ibiapina, por meio do comunicador Jardele.<br \/>\nO primeiro dia dos festejos foi encerrado com a anima\u00e7\u00e3o mission\u00e1ria de Alexandre Melo, que conduziu a comunidade em um clima de louvor e miss\u00e3o, renovando a f\u00e9 e a alegria dos devotos da padroeira.<\/p>\n<div id='gallery-1' class='gallery galleryid-35165 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-1\/'><img loading=\"lazy\" width=\"300\" height=\"223\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-300x223.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (1)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-300x223.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-1024x761.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-768x571.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-1536x1142.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-1-2048x1523.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-2\/'><img loading=\"lazy\" width=\"300\" height=\"197\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-300x197.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (2)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-300x197.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-1024x672.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-768x504.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-1536x1008.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-2-2048x1344.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-3\/'><img loading=\"lazy\" width=\"300\" height=\"208\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-3-300x208.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (3)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-3-300x208.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-3-1024x711.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-3-768x533.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-3.jpeg 1337w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-4\/'><img loading=\"lazy\" width=\"300\" height=\"217\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-300x217.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (4)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-300x217.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-1024x741.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-768x556.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-1536x1111.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-4-2048x1482.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-5\/'><img loading=\"lazy\" width=\"300\" height=\"216\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-300x216.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (5)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-300x216.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-1024x738.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-768x554.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-1536x1108.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-5-2048x1477.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-6\/'><img loading=\"lazy\" width=\"300\" height=\"217\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-300x217.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (6)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-300x217.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-1024x740.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-768x555.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-1536x1110.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-6-2048x1480.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-7\/'><img loading=\"lazy\" width=\"300\" height=\"210\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-300x210.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (7)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-300x210.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-1024x718.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-768x539.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-1536x1078.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-7-2048x1437.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-8\/'><img loading=\"lazy\" width=\"300\" height=\"204\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-300x204.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (8)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-300x204.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-1024x698.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-768x524.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-1536x1047.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-2048x1396.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-9\/'><img loading=\"lazy\" width=\"300\" height=\"218\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-300x218.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (9)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-300x218.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-1024x743.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-768x557.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-1536x1114.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-9-2048x1485.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-10\/'><img loading=\"lazy\" width=\"300\" height=\"208\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-300x208.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (10)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-300x208.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-1024x709.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-768x532.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-1536x1063.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-10-2048x1418.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-11\/'><img loading=\"lazy\" width=\"300\" height=\"221\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-300x221.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (11)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-300x221.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-1024x753.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-768x565.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-1536x1130.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-11-2048x1507.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/jordao-abre-festa-de-nossa-senhora-da-saude-2025-com-fe-musica-e-missao\/pag-6-jornal-12\/'><img loading=\"lazy\" width=\"300\" height=\"209\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-300x209.jpeg\" class=\"attachment-medium size-medium\" alt=\"pag 6 jornal (12)\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-300x209.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-1024x712.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-768x534.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-1536x1068.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-12-2048x1424.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quinta-feira, 14 de agosto, a comunidade de Jord\u00e3o deu in\u00edcio \u00e0 tradicional&#8230;<\/p>\n","protected":false},"author":7,"featured_media":35173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-35165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-scaled.jpeg",2560,1745,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-150x150.jpeg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-300x204.jpeg",300,204,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-768x524.jpeg",640,437,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-1024x698.jpeg",640,436,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-1536x1047.jpeg",1536,1047,true],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-2048x1396.jpeg",2048,1396,true],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-1024x698.jpeg",1024,698,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-540x340.jpeg",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/pag-6-jornal-8-scaled.jpeg","jetpack-related-posts":[{"id":34869,"url":"https:\/\/correiodasemana.com\/site\/festa-de-nossa-senhora-da-saude-de-jordao-2025-fe-tradicao-e-cultura\/","url_meta":{"origin":35165,"position":0},"title":"Festa de Nossa Senhora da Sa\u00fade de Jord\u00e3o 2025: F\u00e9, Tradi\u00e7\u00e3o e Cultura","author":"adminredacao","date":"Julho 28, 2025","format":false,"excerpt":"Entre os dias 14 e 24 de agosto de 2025, o Distrito de Jord\u00e3o, em Sobral, vivenciar\u00e1 intensamente a Festa de Nossa Senhora da Sa\u00fade, um dos eventos religiosos mais tradicionais da regi\u00e3o. Com o tema \u201cNossa Senhora da Sa\u00fade: disc\u00edpula e peregrina da Esperan\u00e7a\u201d, a celebra\u00e7\u00e3o dos festejos promete\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/festa-nossa-senhora-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/festa-nossa-senhora-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/festa-nossa-senhora-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/festa-nossa-senhora-2.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35399,"url":"https:\/\/correiodasemana.com\/site\/festa-da-padroeira-de-jordao-e-encerrada-com-jubilo-e-grandes-atracoes-religiosas\/","url_meta":{"origin":35165,"position":1},"title":"Festa da Padroeira de Jord\u00e3o \u00e9 encerrada com j\u00fabilo e grandes atra\u00e7\u00f5es religiosas","author":"adminredacao","date":"Setembro 1, 2025","format":false,"excerpt":"Toda a regi\u00e3o voltou-se para o Distrito de Jord\u00e3o, que celebrou com f\u00e9 e entusiasmo o encerramento da Festa de Nossa Senhora da Sa\u00fade 2025. Desde o dia 14 de agosto, a pra\u00e7a da Igreja Matriz tornou-se palco do maior evento religioso e cultural de toda a serra, reunindo fi\u00e9is,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-08-27-at-20.28.14-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-08-27-at-20.28.14-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-08-27-at-20.28.14-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-08-27-at-20.28.14-3.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-08-27-at-20.28.14-3.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8540,"url":"https:\/\/correiodasemana.com\/site\/regioes-episcopais-6\/","url_meta":{"origin":35165,"position":2},"title":"Regi\u00f5es Episcopais","author":"","date":"Agosto 6, 2019","format":false,"excerpt":"Par\u00f3quia Nossa Senhora do Perp\u00e9tuo Socorro \u2013 Reriutaba \u2013 CE Os festejos da Par\u00f3quia de Reriutaba iniciam no dia 5 de agosto. Acompanhe abaixo o convite do P\u00e1roco Padre Eufrazio da Silva e do Conselho Paroquial. Car\u00edssimos Paroquianos, chegamos a mais um momento de gra\u00e7a em nossa Par\u00f3quia. Eis um\u2026","rel":"","context":"In &quot;Diocese&quot;","block_context":{"text":"Diocese","link":"https:\/\/correiodasemana.com\/site\/category\/diocese\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/igreja-do-ros%C3%A1rio.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/igreja-do-ros%C3%A1rio.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/igreja-do-ros%C3%A1rio.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/igreja-do-ros%C3%A1rio.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8368,"url":"https:\/\/correiodasemana.com\/site\/regioes-episcopais-4\/","url_meta":{"origin":35165,"position":3},"title":"Regi\u00f5es Episcopais","author":"","date":"Julho 22, 2019","format":false,"excerpt":"Par\u00f3quia de Sant\u2019Ana \u2013 EM Santana do Acara\u00fa \u2013 CE FESTA DE SANT\u2019ANA 2019 Queridos amigos e amigas santanenses e visitantes devotos de Sant\u2019Ana, louvado seja Nosso Senhor Jesus Cristo! \u00c9 com imensa alegria que os convido a participarem conosco da Festa de nossa muito amada padroeira Senhora Sant\u2019Ana, momento\u2026","rel":"","context":"In &quot;Igreja&quot;","block_context":{"text":"Igreja","link":"https:\/\/correiodasemana.com\/site\/category\/igreja\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja-da-Se%CC%81-Sobral.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":30317,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-sobral-area-pastoral-nossa-senhora-da-saude-festa-de-nossa-senhora-da-saude-2024-jordao-sobral-ce\/","url_meta":{"origin":35165,"position":4},"title":"DIOCESE DE SOBRAL \u00c1REA PASTORAL NOSSA SENHORA DA SA\u00daDE FESTA DE NOSSA SENHORA DA SA\u00daDE -2024 JORD\u00c3O &#8211; SOBRAL \u2013 CE","author":"adminredacao","date":"Agosto 12, 2024","format":false,"excerpt":"Amados paroquianos, devotos, visitantes, amigos, benfeitores e povo de Deus! Sauda\u00e7\u00f5es em Cristo! \u201cEu vim de l\u00e1 do interior Aonde a religi\u00e3o ainda \u00e9 importante. L\u00e1 se algu\u00e9m passa em frente da matriz se benze e pensa em Deus e n\u00e3o sente vergonha de ter f\u00e9\u201d (Padre Zezinho) Agosto chegou!\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-08-at-18.56.59-scaled.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-08-at-18.56.59-scaled.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-08-at-18.56.59-scaled.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-08-at-18.56.59-scaled.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-08-at-18.56.59-scaled.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16865,"url":"https:\/\/correiodasemana.com\/site\/as-festividades-juninas\/","url_meta":{"origin":35165,"position":5},"title":"As festividades juninas","author":"","date":"Junho 27, 2021","format":false,"excerpt":"Estamos vivenciando o m\u00eas das festas juninas, um tempo no qual as tradi\u00e7\u00f5es religiosas e populares se misturam. \u00c9 uma oportunidade de valorizarmos a nossa cultura com toda a sua riqueza. Tais festas possuem origem antiga, quando os povos pag\u00e3os festejavam o solst\u00edcio de ver\u00e3o, ou seja, o dia mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=35165"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35165\/revisions"}],"predecessor-version":[{"id":35178,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35165\/revisions\/35178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/35173"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=35165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=35165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=35165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}