{"id":35573,"date":"2025-09-15T15:05:08","date_gmt":"2025-09-15T18:05:08","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=35573"},"modified":"2025-09-15T15:05:08","modified_gmt":"2025-09-15T18:05:08","slug":"confira-as-penas-de-bolsonaro-e-mais-sete-condenados-pelo-supremo","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/confira-as-penas-de-bolsonaro-e-mais-sete-condenados-pelo-supremo\/","title":{"rendered":"Confira as penas de Bolsonaro e mais sete condenados pelo Supremo"},"content":{"rendered":"<p><strong>Primeira Turma finalizou julgamento da a\u00e7\u00e3o da trama golpista<\/strong><\/p>\n<p>Andr\u00e9 Richter &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<\/p>\n<p>A Primeira Turma do Supremo Tribunal Federal (STF) finalizou nesta quinta-feira (11) o julgamento da a\u00e7\u00e3o da trama golpista.<br \/>\nPor 4 votos a 1, os\u00a0ministros condenaram o ex-presidente Jair Bolsonaro\u00a0e mais sete aliados pelos crimes de organiza\u00e7\u00e3o criminosa armada, tentativa de aboli\u00e7\u00e3o violenta do Estado Democr\u00e1tico de Direito, golpe de Estado, dano qualificado pela viol\u00eancia e grave amea\u00e7a e deteriora\u00e7\u00e3o de patrim\u00f4nio tombado.<br \/>\nA maioria dos r\u00e9us foi condenada a mais de 20 anos de pris\u00e3o em regime fechado.<br \/>\nApesar da defini\u00e7\u00e3o do tempo de condena\u00e7\u00e3o, Bolsonaro e os demais r\u00e9us n\u00e3o v\u00e3o ser presos imediatamente. Eles ainda\u00a0podem recorrer da decis\u00e3o e tentar reverter as condena\u00e7\u00f5es. Somente se os eventuais recursos forem rejeitados, as pris\u00f5es poder\u00e3o ser efetivadas.<br \/>\nConfira as penas definidas para os condenados:<br \/>\n&#8211; Jair Bolsonaro \u2013 ex-presidente da Rep\u00fablica:\u00a027 anos e tr\u00eas meses;<br \/>\n&#8211; Walter Braga Netto &#8211; ex-ministro de Bolsonaro e candidato a\u00a0vice-presidente na chapa de 2022:\u00a026 anos;<br \/>\n&#8211; Almir Garnier &#8211; ex-comandante da Marinha:\u00a024 anos;<br \/>\n&#8211; Anderson Torres &#8211; ex-ministro da Justi\u00e7a e ex-secret\u00e1rio de seguran\u00e7a do Distrito Federal: 24 anos;<br \/>\n&#8211; Augusto Heleno &#8211; ex-ministro do Gabinete de Seguran\u00e7a Institucional (GSI):\u00a021 anos;<br \/>\n&#8211; Paulo S\u00e9rgio Nogueira &#8211; ex-ministro da Defesa:\u00a019 anos;<br \/>\n&#8211; Mauro Cid \u2013 ex-ajudante de ordens de Bolsonaro.\u00a02 anos em regime aberto e garantia de liberdade pela dela\u00e7\u00e3o premiada;<br \/>\n&#8211; Alexandre Ramagem &#8211; ex-diretor da Ag\u00eancia Brasileira de Intelig\u00eancia (Abin): 16 anos, um m\u00eas e 15 dias.<br \/>\nRamagem foi condenado somente pelos crimes de organiza\u00e7\u00e3o criminosa armada, tentativa de aboli\u00e7\u00e3o violenta do Estado Democr\u00e1tico de Direito e golpe de Estado.<br \/>\nEle \u00e9 deputado federal e teve parte das acusa\u00e7\u00f5es suspensas. A medida vale para os crimes de dano qualificado pela viol\u00eancia e grave amea\u00e7a, contra o patrim\u00f4nio da Uni\u00e3o, e com consider\u00e1vel preju\u00edzo para a v\u00edtima e deteriora\u00e7\u00e3o de patrim\u00f4nio tombado, ambos relacionados aos atos golpistas de 8 de janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primeira Turma finalizou julgamento da a\u00e7\u00e3o da trama golpista Andr\u00e9 Richter &#8211; Rep\u00f3rter da Ag\u00eancia&#8230;<\/p>\n","protected":false},"author":7,"featured_media":35574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-35573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs.webp",1170,700,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-150x150.webp",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-300x179.webp",300,179,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-768x459.webp",640,383,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-1024x613.webp",640,383,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs.webp",1170,700,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs.webp",1170,700,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-1024x613.webp",1024,613,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs-540x340.webp",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/condenacao_de_bolsonaro_e_aliadospixs.webp","jetpack-related-posts":[{"id":35590,"url":"https:\/\/correiodasemana.com\/site\/por-4-a-1-stf-condena-bolsonaro-e-mais-sete-pela-trama-golpista\/","url_meta":{"origin":35573,"position":0},"title":"Por 4 a 1, STF condena Bolsonaro e mais sete pela trama golpista","author":"adminredacao","date":"Setembro 15, 2025","format":false,"excerpt":"Penas ser\u00e3o definidas em seguida pelos ministros POR Andr\u00e9 Richter - Rep\u00f3rter da Ag\u00eancia Brasil Por 4 votos a 1, a Primeira Turma do Supremo Tribunal Federal (STF) condenou o ex-presidente Jair Bolsonaro\u00a0por tentativa de golpe de Estado e outros quatro crimes, sob acusa\u00e7\u00e3o de\u00a0liderar uma trama para permanecer no\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24726,"url":"https:\/\/correiodasemana.com\/site\/stf-forma-maioria-para-condenar-fernando-collor-por-esquema-de-corrupcao\/","url_meta":{"origin":35573,"position":1},"title":"STF forma maioria para condenar Fernando Collor por esquema de corrup\u00e7\u00e3o","author":"","date":"Maio 19, 2023","format":false,"excerpt":"O plen\u00e1rio do Supremo Tribunal Federal (STF) formou maioria nesta quinta-feira, 18 de maio, pela condena\u00e7\u00e3o do ex-presidente Fernando Collor de Mello (PTB) pelos crimes de corrup\u00e7\u00e3o passiva e lavagem de dinheiro - a Corte julga uma a\u00e7\u00e3o penal em que o ex-senador e outras dois r\u00e9us, Luis Pereira Duarte\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/collor-senador-e1684345757371-848x477-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/collor-senador-e1684345757371-848x477-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/collor-senador-e1684345757371-848x477-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/collor-senador-e1684345757371-848x477-1.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25489,"url":"https:\/\/correiodasemana.com\/site\/por-5-votos-a-2-tse-torna-bolsonaro-inelegivel-por-oito-anos\/","url_meta":{"origin":35573,"position":2},"title":"Por 5 votos a 2, TSE torna Bolsonaro ineleg\u00edvel por oito anos","author":"adminredacao","date":"Julho 3, 2023","format":false,"excerpt":"Ex-presidente s\u00f3 poder\u00e1 voltar a disputar elei\u00e7\u00e3o em outubro de 2030 Por Andr\u00e9 Richter - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia Por 5 votos a 2, o Tribunal Superior Eleitoral (TSE) condenou, nesta sexta-feira (30), o ex-presidente Jair Bolsonaro \u00e0 inelegibilidade pelo per\u00edodo de oito anos. Com o entendimento, o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/julgamento-tse-bolsonaro_mcamgo_abr_30062023-14.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/julgamento-tse-bolsonaro_mcamgo_abr_30062023-14.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/julgamento-tse-bolsonaro_mcamgo_abr_30062023-14.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/julgamento-tse-bolsonaro_mcamgo_abr_30062023-14.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/julgamento-tse-bolsonaro_mcamgo_abr_30062023-14.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22736,"url":"https:\/\/correiodasemana.com\/site\/agu-pede-o-bloqueio-de-bens-de-financiadores-dos-atos-golpistas\/","url_meta":{"origin":35573,"position":3},"title":"AGU pede o bloqueio de bens de financiadores dos atos golpistas","author":"adminredacao","date":"Janeiro 15, 2023","format":false,"excerpt":"A Advocacia-Geral da Uni\u00e3o (AGU) pediu hoje (12) o bloqueio de bens de 52 pessoas f\u00edsicas e sete jur\u00eddicas, num total de R$ 6.539.100. Segundo o \u00f3rg\u00e3o, os alvos s\u00e3o respons\u00e1veis por pagar o fretamento de \u00f4nibus para trazer pessoas para participar dos atos de vandalismos ocorridos em Bras\u00edlia no\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AGU-.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AGU-.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AGU-.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/AGU-.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24443,"url":"https:\/\/correiodasemana.com\/site\/stf-anula-indulto-de-bolsonaro-a-daniel-silveira\/","url_meta":{"origin":35573,"position":4},"title":"STF anula indulto de Bolsonaro a Daniel Silveira","author":"","date":"Maio 5, 2023","format":false,"excerpt":"O Supremo Tribunal Federal (STF) formou maioria nesta quinta-feira, 4 de maio, e anulou o decreto de indulto individual concedido em 2022 pelo ex-presidente Jair Bolsonaro (PL) ao ent\u00e3o deputado federal Daniel Silveira (PTB). Os ministros Alexandre de Moraes, Lu\u00eds Roberto Barroso, Edson Fachin, Dias Toffoli e C\u00e1rmen L\u00facia acompanharam\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img20191211185946761_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img20191211185946761_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img20191211185946761_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img20191211185946761_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img20191211185946761_0.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9563,"url":"https:\/\/correiodasemana.com\/site\/stf-suspende-julgamento-de-prisao-apos-condenacao-em-segunda-instancia\/","url_meta":{"origin":35573,"position":5},"title":"STF suspende julgamento de pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"Por\u00a0Andr\u00e9 Richter \u2013 Rep\u00f3rter da Ag\u00eancia Brasil\u00a0\u00a0Bras\u00edlia O ministro do Supremo Tribunal Federal (STF) Ricardo Lewandowski votou dia (24) contra a validade da execu\u00e7\u00e3o provis\u00f3ria de condena\u00e7\u00f5es criminais, conhecida como pris\u00e3o ap\u00f3s segunda inst\u00e2ncia. Com o voto do ministro, ap\u00f3s quatro sess\u00f5es de julgamento, o placar est\u00e1 4 votos a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/edit_fcpzzb_abr_241020196172.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=35573"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35573\/revisions"}],"predecessor-version":[{"id":35575,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35573\/revisions\/35575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/35574"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=35573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=35573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=35573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}