{"id":35588,"date":"2025-09-15T15:08:25","date_gmt":"2025-09-15T18:08:25","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=35588"},"modified":"2025-09-15T15:08:25","modified_gmt":"2025-09-15T18:08:25","slug":"de-olho-na-lingua-135","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-135\/","title":{"rendered":"De Olho na L\u00edngua"},"content":{"rendered":"<p>\u201cEle desceu ladeira a baixo\u201d ou \u201cEle desceu ladeira abaixo\u201d?<br \/>\nA frase correta \u00e9: \u201cEle desceu ladeira a baixo\u201d. Abaixo = embaixo, sob. Ex.: Sua classifica\u00e7\u00e3o foi abaixo da minha. A baixo = para baixo, at\u00e9 embaixo. Ex.: Eles puseram o apartamento a baixo; Ela me olhava de alto a baixo.<\/p>\n<p>Abaixo-assinado ou abaixo assinado<br \/>\nAmbas corretas, mas com sentido diferente. Abaixo-assinado (com h\u00edfen) \u00e9 o documento que se assina: Entregamos o abaixo-assinado ao diretor executivo. Abaixo assinado (sem h\u00edfen) refere-se aos signat\u00e1rios desse documento podendo variar em g\u00eanero e n\u00famero: abaixo assinada; abaixo assinados.<\/p>\n<p>\u201cA n\u00edvel de\u201d e \u201cEm n\u00edvel de\u201d<br \/>\nO uso mais adequado, segundo a Gram\u00e1tica Normativa, \u00e9 \u201cem n\u00edvel de\u201d, para indicar o \u00e2mbito ou plano de algo, ou \u201cao n\u00edvel de\u201d, quando se refere \u00e0 mesma altura ou grau.<br \/>\nA express\u00e3o \u201ca n\u00edvel de\u201d \u00e9 considerada incorreta e deve ser evitado em situa\u00e7\u00f5es formais, pois \u00e9 um uso considerados desnecess\u00e1rio e n\u00e3o se alinha com a norma culta da L\u00edngua Portuguesa. Ex.: O problema precisa ser discutido em n\u00edvel de diretoria. \u201cAo n\u00edvel de\u201d, ex.: A cidade litor\u00e2nea fica ao n\u00edvel do mar; Ele n\u00e3o estava ao n\u00edvel (a altura) de sua capacidade.<\/p>\n<p>Mais \/ Mas \/ M\u00e1s<br \/>\nMais &#8211; op\u00f5e-se a menos. Ex.: Hoje estou mais satisfeito que (ou do que) ontem. Mas &#8211; conjun\u00e7\u00e3o adversativa e sin\u00f4nimo de por\u00e9m, todavia, entretanto, sen\u00e3o. Ex.: N\u00e3o foram convidados, mas vieram \u00e0 festa. M\u00e1s \u00e9 o plural do adjetivo \u201cm\u00e1\u201d e op\u00f5e-se a boas. Exs.: N\u00e3o eram m\u00e1s ideias (eram boas ideias); Estavam com m\u00e1s inten\u00e7\u00f5es (n\u00e3o tinham boas inten\u00e7\u00f5es.<\/p>\n<p>Pode ou podem haver mais acidentes?<br \/>\nO correto \u00e9: Pode haver mais acidentes. O verbo haver, no sentido de existir, deve ser usado sempre no singular. O mesmo ocorrer\u00e1 quando o verbo haver for verbo principal de uma locu\u00e7\u00e3o verbal. Locu\u00e7\u00e3o verbal \u00e9 o resultado de quando juntamos dois ou mais verbos. O verbo principal \u00e9 o \u00faltimo. Veja mais exemplos ainda: Ainda deve haver algumas vagas nesta escola; Poderia ter havido muitos acidentes nesta chuva.<\/p>\n<p>\u201cO escolhido foi eu\u201d ou \u201cO escolhido fui eu\u201d?<br \/>\nO correto \u00e9: O escolhido fui eu (= Eu fui o escondido). Ningu\u00e9m diz: Eu foi o escolhido.<br \/>\nAuto escola \/ Auto-Escola ou Autoescola?<br \/>\nA \u00fanica correta \u00e9 Autoescola (a inicial mai\u00fascula e o restante da palavra em min\u00fasculas). Isso se deve \u00e0s regras do Acordo Ortogr\u00e1fico da L\u00edngua Portuguesa (AO\/90) que determina a jun\u00e7\u00e3o de prefixos (com \u201cauto\u201d) a palavras que come\u00e7am com vogais diferentes. Vejamos outros exemplos: autoestima, autoinstru\u00e7\u00e3o, autoatendimento, autoajuda, autoan\u00e1lise, etc.<\/p>\n<p>Alto \/ Auto<br \/>\nA palavra auto (grafada com u) tem como origem o termo em Latim \u201coctum\u201d, se referindo a um ato p\u00fablico ou registro detalhado. Tamb\u00e9m pode ser a forma abreviada para autom\u00f3vel. Al\u00e9m disso, \u00e9 um prefixo grego que tem como significado as express\u00f5es \u201csi mesmo\u201d, \u201csi pr\u00f3prio\u201d. Exs.: Atualmente estou com minha autoestima muito baixo; Voc\u00ea j\u00e1 realizou alguma sess\u00e3o de auto-hipnose.<br \/>\nAlto (grafado com l) descende do termo em Latim \u201caltus\u201d (grande, elevado, superior, forte). Por isso, vem sempre grafado com a letra l (de sua origem). Alto \u00e9 ant\u00f4nimo de baixo.<\/p>\n<p>(*) Professor Ant\u00f4nio da Costa \u00e9 graduado em Letras Plenas, com Especializa\u00e7\u00e3o em L\u00edngua Portuguesa e Literatura, na Universidade Estadual Vale do Acara\u00fa (UVA). Contatos: (088) 99373-7724.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEle desceu ladeira a baixo\u201d ou \u201cEle desceu ladeira abaixo\u201d? A frase correta \u00e9: \u201cEle&#8230;<\/p>\n","protected":false},"author":7,"featured_media":17923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,12],"tags":[],"class_list":["post-35588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-de-olho-na-lingua"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/\" rel=\"category tag\">De olho na l\u00edngua<\/a>","tag_info":"De olho na l\u00edngua","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg","jetpack-related-posts":[{"id":38203,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-155\/","url_meta":{"origin":35588,"position":0},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Abril 19, 2026","format":false,"excerpt":"A minha irm\u00e3 \u00e9 \u201cque nem eu\u201d O que voc\u00ea acha dessa express\u00e3o? Em princ\u00edpio n\u00e3o vejo erro, muito embora os puristas da L\u00edngua n\u00e3o vejam assim. \u201cQue nem eu\u201d \u00e9 uma express\u00e3o comparativa igual a \u201ccomo\u201d. \u00c9 express\u00e3o da linguagem popular, do cotidiano. Al\u00e9m do mais, alguns bons escritores\u2026","rel":"","context":"In &quot;De olho na l\u00edngua&quot;","block_context":{"text":"De olho na l\u00edngua","link":"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17415,"url":"https:\/\/correiodasemana.com\/site\/maioria-dos-acudes-do-ceara-esta-em-situacao-critica-de-reserva-de-agua-com-niveis-abaixo-de-30\/","url_meta":{"origin":35588,"position":1},"title":"Maioria dos a\u00e7udes do Cear\u00e1 est\u00e1 em situa\u00e7\u00e3o cr\u00edtica de reserva de \u00e1gua com n\u00edveis abaixo de 30%","author":"","date":"Setembro 6, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo dados do Portal Hidrol\u00f3gico do Estado, gerenciado pela Companhia de Gest\u00e3o dos Recursos H\u00eddricos (Cogerh), extra\u00eddos na \u00faltima quarta-feira (01) a maioria dos reservat\u00f3rios do Cear\u00e1 est\u00e3o em n\u00edvel cr\u00edtico de volume h\u00eddrico. De acordo com a plataforma, dos 66 a\u00e7udes monitorados,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":33575,"url":"https:\/\/correiodasemana.com\/site\/maioria-no-pais-alunos-mais-pobres-tem-menor-aprendizado-em-leitura\/","url_meta":{"origin":35588,"position":2},"title":"Maioria no pa\u00eds, alunos mais pobres t\u00eam menor aprendizado em leitura","author":"adminredacao","date":"Abril 29, 2025","format":false,"excerpt":"Apenas um quarto deles alcan\u00e7a n\u00edvel adequado no 4\u00ba ano do fundamental POR Mariana Tokarnia - Rep\u00f3rter da Ag\u00eancia Brasil Os estudantes com menor n\u00edvel socioecon\u00f4mico (NSE) t\u00eam pior desempenho em leitura, e quase metade deles tem n\u00edvel de aprendizado considerado \u201cabaixo do b\u00e1sico\u201d.\u00a0No Brasil, enquanto 83,9% dos alunos do\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/DSC_0179-1024x678-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/DSC_0179-1024x678-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/DSC_0179-1024x678-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/DSC_0179-1024x678-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30347,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-96\/","url_meta":{"origin":35588,"position":3},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Agosto 12, 2024","format":false,"excerpt":"Cac\u00f3fato (O que \u00e9 isso?) Cac\u00f3fato \u00e9 som feio, desagrad\u00e1vel, obsceno ou com sentido equ\u00edvoco, produzido pela uni\u00e3o de s\u00edlabas de duas palavras vizinhas. Conv\u00e9m evit\u00e1-los! Vejamos: O jogador pediu a bola e Cafu deu; Cuba lan\u00e7ou o novo programa; Isto \u00e9 para sacar alho; \u00c9 uma tem\u00e1tica gay; Ele\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24803,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-53\/","url_meta":{"origin":35588,"position":4},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 21, 2023","format":false,"excerpt":"\u201cMeu carro foi lavado no Lava Jato X\u201d Diga corretamente: \u201cMeu carro foi lavado no Java a Jato X\u201d (sem h\u00edfen). Lava Jato \u00e9 o nome da \u201cOpera\u00e7\u00e3o Lava Jato\u201d, que a PF organizou para desbaratar o esquema montado por alguns figur\u00f5es para \u201clavar\u201d dinheiro ganho ilicitamente. Infelizmente, como quase\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":37451,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-150\/","url_meta":{"origin":35588,"position":5},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Fevereiro 20, 2026","format":false,"excerpt":"Carnaval (Etimologia) Deriva do Latim \u201cCarrus Navalis\u201d, pelo italiano \u201ccarnavale\u201d, por sua vez radicado na express\u00e3o latina \u201ccarne vale\u201d (adeus carne) ou \u201ccarne levare\u201d (prazeres da carne), designando os festejos dos dias que antecedem a entrada da Quaresma. Tamb\u00e9m conhecido como \u201centrudo\u201d, do Latim \u201cintroitos\u201d (entrada). Do Latim \u201cCarrus Navalis\u201d\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=35588"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35588\/revisions"}],"predecessor-version":[{"id":35589,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35588\/revisions\/35589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17923"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=35588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=35588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=35588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}