{"id":35832,"date":"2025-10-13T16:10:28","date_gmt":"2025-10-13T19:10:28","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=35832"},"modified":"2025-10-13T16:10:28","modified_gmt":"2025-10-13T19:10:28","slug":"aparecida-nas-aguas-5","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-5\/","title":{"rendered":"Aparecida nas \u00e1guas"},"content":{"rendered":"<p>Neste domingo, dia 12, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais uma vez, colocava-se ao lado dos mais pobres e oprimidos, intercedendo por suas dores.<br \/>\nDe fato, a hist\u00f3ria de Nossa Senhora Aparecida muito nos questiona, ao percebermos o que aquela pesca milagrosa significou para a hist\u00f3ria do povo brasileiro. Pelas m\u00e3os de tr\u00eas pescadores, surgiu um dos s\u00edmbolos mais belos da cultura e da f\u00e9 de nosso povo. Mais do que uma imagem, a 12 de outubro de 1717, surgiu vida nova nas \u00e1guas do Rio Para\u00edba do Sul.<br \/>\nSurgiu vida nova para um povo oprimido pelas injusti\u00e7as sociais, assolado pela cruel escravid\u00e3o e pela \u00e1spera realidade da pobreza. Uma imagem quebrada e enegrecida pelo barro da lama nos sugere uma rica simbologia, pois esse \u00e9 o retrato fiel de milh\u00f5es de brasileiros de ontem e de hoje. E, ent\u00e3o, o C\u00e9u nos consola: Maria desce \u00e0 lama, ao fundo das \u00e1guas existenciais de uma na\u00e7\u00e3o enlameada pelas desigualdades e injusti\u00e7as sociais.<br \/>\nE essa realidade n\u00e3o ficou no passado, mas mostra qu\u00e3o atual \u00e9 a mensagem consoladora de Aparecida. A imagem pequenina e restaurada nos ensina a ser um povo que n\u00e3o sabe esmorecer. E mesmo que seja ferido, esmagado e machucado, tal como a imagem da padroeira, \u00e9 um povo de f\u00e9, que sabe renascer.<br \/>\nNesse sentido, percebemos o quanto a imagem de Aparecida tem a nos ensinar a partir dos misteriosos des\u00edgnios de Deus, que exalta os humildes. A imagem de cor negra, pequenina e fr\u00e1gil, t\u00e3o venerada por esta na\u00e7\u00e3o afora, recebe uma coroa ofertada pela Princesa Isabel em 1904, e torna-se a Rainha do Brasil e, em 1930, \u00e9 proclamada solenemente, pelo Papa Pio XI, a padroeira de nossa p\u00e1tria. Muito nos consola a certeza de que a pr\u00f3pria Virgem Maria, a M\u00e3e Aparecida, \u00e9 a Rainha de nosso pa\u00eds. De fato, a hist\u00f3ria de Maria \u00e9 a hist\u00f3ria do povo humilde. Continua at\u00e9 hoje nas pequenas e nas grandes hist\u00f3rias de tantos brasileiros que sonham com um pa\u00eds melhor, mais unido, pac\u00edfico, fraterno e solid\u00e1rio. Ela continua sendo a porta-voz da esperan\u00e7a de um povo! Que Nossa Senhora derrame muitas b\u00ean\u00e7\u00e3os sobre todo o Brasil, que a venera como padroeira em sua imagem pequenina, fr\u00e1gil e enegrecida. E que nos confirme em nosso ideal crist\u00e3o de amar a todos, especialmente os pequeninos e pobres de nossa na\u00e7\u00e3o!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, dia 12, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora&#8230;<\/p>\n","protected":false},"author":7,"featured_media":75,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,20],"tags":[],"class_list":["post-35832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs-300x192.jpg",300,192,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",620,397,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg",531,340,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/editorial\/\" rel=\"category tag\">Editorial<\/a>","tag_info":"Editorial","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg","jetpack-related-posts":[{"id":14199,"url":"https:\/\/correiodasemana.com\/site\/uma-imagem-aparecida-nas-aguas\/","url_meta":{"origin":35832,"position":0},"title":"Uma imagem aparecida nas \u00e1guas","author":"","date":"Outubro 20, 2020","format":false,"excerpt":"No \u00faltimo dia 12, feriado nacional, a Igreja do Brasil celebrou a festa da Rainha e Padroeira desta na\u00e7\u00e3o, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17803,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas\/","url_meta":{"origin":35832,"position":1},"title":"APARECIDA NAS \u00c1GUAS","author":"","date":"Outubro 18, 2021","format":false,"excerpt":"No \u00faltimo dia 12, feriado nacional, a Igreja do Brasil celebrou a festa da Rainha e Padroeira desta na\u00e7\u00e3o, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":26835,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-3\/","url_meta":{"origin":35832,"position":2},"title":"Aparecida nas \u00e1guas","author":"adminredacao","date":"Outubro 17, 2023","format":false,"excerpt":"No \u00faltimo dia 12, feriado nacional, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais uma vez, colocava-se ao\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":31055,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-4\/","url_meta":{"origin":35832,"position":3},"title":"Aparecida nas \u00e1guas","author":"adminredacao","date":"Outubro 21, 2024","format":false,"excerpt":"Neste s\u00e1bado, dia 12, feriado nacional, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais uma vez, colocava-se ao\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":21239,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-2\/","url_meta":{"origin":35832,"position":4},"title":"Aparecida nas \u00e1guas","author":"","date":"Outubro 10, 2022","format":false,"excerpt":"No pr\u00f3ximo dia 12, feriado nacional, a Igreja do Brasil celebra a festa da Rainha e Padroeira desta na\u00e7\u00e3o, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":35834,"url":"https:\/\/correiodasemana.com\/site\/aparecida-sacramento-profecia-e-missao-para-o-povo-brasileiro\/","url_meta":{"origin":35832,"position":5},"title":"Aparecida: sacramento, profecia e miss\u00e3o para o povo brasileiro\u00a0","author":"adminredacao","date":"Outubro 13, 2025","format":false,"excerpt":"Reunimo-nos, mais uma vez, sob o olhar terno e materno da Virgem Aparecida, para celebrar a grande Solenidade de nossa Padroeira. Este dia, 12 de outubro, transcende a mera contagem do tempo \u2013 o\u00a0chronos\u00a0de nosso calend\u00e1rio \u2013 para se tornar um verdadeiro\u00a0kair\u00f3s: um tempo de gra\u00e7a, um momento significativo em\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=35832"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35832\/revisions"}],"predecessor-version":[{"id":35833,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35832\/revisions\/35833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=35832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=35832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=35832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}