{"id":35834,"date":"2025-10-13T16:11:06","date_gmt":"2025-10-13T19:11:06","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=35834"},"modified":"2025-10-13T16:11:06","modified_gmt":"2025-10-13T19:11:06","slug":"aparecida-sacramento-profecia-e-missao-para-o-povo-brasileiro","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/aparecida-sacramento-profecia-e-missao-para-o-povo-brasileiro\/","title":{"rendered":"Aparecida: sacramento, profecia e miss\u00e3o para o povo brasileiro\u00a0"},"content":{"rendered":"<p>Reunimo-nos, mais uma vez, sob o olhar terno e materno da Virgem Aparecida, para celebrar a grande Solenidade de nossa Padroeira. Este dia, 12 de outubro, transcende a mera contagem do tempo \u2013 o\u00a0chronos\u00a0de nosso calend\u00e1rio \u2013 para se tornar um verdadeiro\u00a0kair\u00f3s: um tempo de gra\u00e7a, um momento significativo em que o c\u00e9u toca a terra e a hist\u00f3ria da salva\u00e7\u00e3o se revela com um sotaque inconfundivelmente brasileiro. Aqui, na casa da M\u00e3e, n\u00e3o celebramos uma mem\u00f3ria distante, mas uma presen\u00e7a viva e atuante que moldou a alma de nossa gente e continua a interpelar o nosso presente e a iluminar o nosso futuro. Nossa miss\u00e3o, nesta solene liturgia, \u00e9 ir al\u00e9m da emo\u00e7\u00e3o devocional, por mais leg\u00edtima que seja, para mergulhar, com a intelig\u00eancia da f\u00e9, no denso conte\u00fado teol\u00f3gico, prof\u00e9tico e mission\u00e1rio que emana deste singular evento de gra\u00e7a ocorrido nas \u00e1guas do Rio Para\u00edba do Sul.<br \/>\nPara compreender Aparecida, devemos situ\u00e1-la no grande fluxo da Hist\u00f3ria da Salva\u00e7\u00e3o. A\u00a0Primeira Leitura, extra\u00edda do Livro de Ester \u2013 Est 5,1b-2;7,2b-3 \u2013, nos oferece a chave de leitura da intercess\u00e3o r\u00e9gia. A Rainha Ester, uma figura de coragem e f\u00e9, arrisca sua vida para salvar seu povo. Sua atitude prefigura a miss\u00e3o de Maria, a Nova Eva, que, ao contr\u00e1rio da primeira, n\u00e3o dialogou com a serpente, mas esmagou sua cabe\u00e7a com o \u201csim\u201d de sua obedi\u00eancia, como prometido no Protoevangelho (cf. Gn 3,15). Maria \u00e9 a Rainha que n\u00e3o intercede diante de um rei terreno, mas se assenta \u00e0 direita de seu Filho, o Rei do Universo, para apresentar-lhe as s\u00faplicas de seus filhos. Como nos ensina o Conc\u00edlio Ecum\u00eanico Vaticano II, na Constitui\u00e7\u00e3o Dogm\u00e1tica\u00a0Lumen Gentium, Maria,\u00a0\u201ccom o seu amor de m\u00e3e, cuida dos irm\u00e3os de seu Filho que ainda peregrinam e se acham em perigos e ansiedades, at\u00e9 que sejam conduzidos \u00e0 p\u00e1tria bem-aventurada\u201d\u00a0(LG, 62).<br \/>\n\u00c9 nesta perspectiva que devemos contemplar o evento de 1717. N\u00e3o foi um acaso. Deus irrompe na hist\u00f3ria concreta, no Brasil Col\u00f4nia, num contexto de dificuldades econ\u00f4micas e de tens\u00f5es sociais, durante a visita do Conde de Assumar, Dom Pedro de Almeida. E o faz da maneira mais desconcertante. A manifesta\u00e7\u00e3o divina n\u00e3o ocorre com pompa, mas na labuta frustrada de tr\u00eas pescadores, homens pobres e an\u00f4nimos, cujos nomes, no entanto, a f\u00e9 fez quest\u00e3o de eternizar: Domingos Garcia, Jo\u00e3o Alves e Filipe Pedroso. Eles s\u00e3o os\u00a0anawim Adonai, os \u201cpobres de Jav\u00e9\u201d, a quem Deus sempre se revela, confirmando o canto prof\u00e9tico da pr\u00f3pria Virgem em seu Magnificat:\u00a0\u201cDep\u00f4s os poderosos de seus tronos e exaltou os humildes. Saciou de bens os indigentes e despediu de m\u00e3os vazias os ricos\u201d\u00a0(Lc 1,52-53).<br \/>\nCada elemento daquele encontro \u00e9 um denso sinal teol\u00f3gico, um evangelho n\u00e3o escrito:<br \/>\nO Rio: \u00c9 o fluxo da vida, da hist\u00f3ria, do trabalho e do suor do povo brasileiro. \u00c9 nas \u00e1guas, s\u00edmbolo do Batismo, que a M\u00e3e da Igreja se deixa encontrar.<br \/>\nA Rede: S\u00edmbolo da miss\u00e3o da Igreja, lan\u00e7ada nas \u00e1guas, por vezes turvas, do mundo. \u00c9 a Igreja-pescadora que, em sua miss\u00e3o, encontra a presen\u00e7a de Maria.<br \/>\nA Imagem Quebrada: Este \u00e9 talvez o mais forte dos s\u00edmbolos. O corpo separado da cabe\u00e7a. \u00c9 o retrato de um Brasil fraturado, de um povo dividido pelo pecado social, pela injusti\u00e7a, pelo abismo entre ricos e pobres.<br \/>\nA Reunifica\u00e7\u00e3o: O reencontro do corpo e da cabe\u00e7a dentro da rede \u00e9 a grande profecia de Aparecida: a voca\u00e7\u00e3o do Brasil \u00e9 a unidade na diversidade, a reconcilia\u00e7\u00e3o. A unidade, como rezou o pr\u00f3prio Cristo, \u00e9 condi\u00e7\u00e3o para a credibilidade da miss\u00e3o: \u201cPara que todos sejam um, a fim de que o mundo creia\u201d (Jo 17,21).<br \/>\nA Cor Negra: A imagem enegrecida \u00e9 um \u00edcone da incultura\u00e7\u00e3o da f\u00e9 e uma den\u00fancia prof\u00e9tica. Maria assume a cor dos filhos mais sofridos, dos escravizados, dos marginalizados. Como nos recorda o Documento de Aparecida, a Igreja na Am\u00e9rica Latina tem uma d\u00edvida hist\u00f3rica com os afrodescendentes e os povos ind\u00edgenas, e \u00e9 chamada a promover \u201co reconhecimento de seus direitos e sua cidadania\u201d (DAp, 96). Nossa Senhora, com sua cor, fez isso antes de n\u00f3s.\u00a0 A Pesca Abundante: A consequ\u00eancia imediata da presen\u00e7a reconciliada da M\u00e3e \u00e9 a abund\u00e2ncia, a gra\u00e7a superabundante. \u00c9 o sinal de que uma na\u00e7\u00e3o e uma Igreja reconciliadas e unidas em Cristo se tornam fecundas e capazes de gerar vida.\u00a0 \u00a0f\u00e9 em Nossa Senhora Aparecida nos convoca a uma leitura cr\u00edtica e prof\u00e9tica da realidade. A mesma M\u00e3e que se compadeceu da necessidade dos noivos em Can\u00e1, hoje se compadece da falta do \u201cvinho da justi\u00e7a, da paz e da dignidade para tantos de seus filhos brasileiros.\u00a0 \u00c9, pois, no Santo Evangelho segundo S\u00e3o Jo\u00e3o \u2013 Jo 2,1-11 \u2013, na narrativa das Bodas de Can\u00e1, que encontramos a s\u00edntese de nossa miss\u00e3o. Diante do problema concreto, Maria nos oferece uma \u00fanica instru\u00e7\u00e3o, um verdadeiro testamento espiritual que se torna o programa pastoral para a Igreja no Brasil:\u00a0\u201cFazei tudo o que Ele vos disser\u201d\u00a0(Jo 2,5). Este mandato nos chama a uma convers\u00e3o radical e a um compromisso mission\u00e1rio em todas as esferas da vida.<\/p>\n<p>Cardeal Orani Jo\u00e3o Tempesta &#8211; Arcebispo do Rio de Janeiro (RJ)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reunimo-nos, mais uma vez, sob o olhar terno e materno da Virgem Aparecida, para celebrar&#8230;<\/p>\n","protected":false},"author":7,"featured_media":7687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[24,11],"tags":[],"class_list":["post-35834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-300x204.jpg",300,204,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-768x523.jpg",640,436,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",640,436,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",499,340,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/\" rel=\"category tag\">A voz do Pastor<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a>","tag_info":"Artigos","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":35953,"url":"https:\/\/correiodasemana.com\/site\/procissao-e-missa-solene-reunem-fieis-na-festa-de-nossa-senhora-aparecida-na-catedral-de-sobral\/","url_meta":{"origin":35834,"position":0},"title":"Prociss\u00e3o e Missa solene re\u00fanem fi\u00e9is na Festa de Nossa Senhora Aparecida na Catedral de Sobral","author":"adminredacao","date":"Outubro 29, 2025","format":false,"excerpt":"A Igreja Cat\u00f3lica no Brasil celebrou, no \u00faltimo s\u00e1bado (12\/10), a Solenidade de Nossa Senhora da Concei\u00e7\u00e3o Aparecida, Rainha e Padroeira do Brasil. Na S\u00e9 Catedral de Sobral, fi\u00e9is se uniram a toda a na\u00e7\u00e3o para entoar c\u00e2nticos e manifestar sua devo\u00e7\u00e3o \u00e0 M\u00e3e de Deus e nossa M\u00e3e. A\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-18-at-15.44.45.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-18-at-15.44.45.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-18-at-15.44.45.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-18-at-15.44.45.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-18-at-15.44.45.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17747,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-sobral-realiza-iv-caminhada-com-maria-2021\/","url_meta":{"origin":35834,"position":1},"title":"Diocese de Sobral realiza IV Caminhada com Maria 2021","author":"","date":"Outubro 17, 2021","format":false,"excerpt":"Por Thais Helena (Portal de Comunica\u00e7\u00e3o \u2013 Diocese de Sobral) Neste ano de modo virtual, a Diocese de Sobral realizou a IV edi\u00e7\u00e3o da Caminhada com Maria, com o tema: \u201cLouvar, bendizer, entoar c\u00e2nticos, salmos e hinos a Deus por meio de Maria\u201d, a Caminhada virtual, no dia 12 de\u2026","rel":"","context":"In &quot;Diocese&quot;","block_context":{"text":"Diocese","link":"https:\/\/correiodasemana.com\/site\/category\/diocese\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IV-CAMINHADA-N-S-APARECIDA-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IV-CAMINHADA-N-S-APARECIDA-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IV-CAMINHADA-N-S-APARECIDA-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IV-CAMINHADA-N-S-APARECIDA-4.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9404,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-preside-missa-solene-em-honra-a-sao-francisco-no-encerramento-dos-festejos\/","url_meta":{"origin":35834,"position":2},"title":"Dom Vasconcelos preside missa solene em honra a S\u00e3o Francisco no encerramento dos festejos","author":"","date":"Outubro 14, 2019","format":false,"excerpt":"Os festejos de S\u00e3o Francisco de Assis foram oficialmente encerrados na sexta-feira (04) com a ben\u00e7\u00e3o aos animais, prociss\u00e3o com a imagem do santo pelas principais ruas da cidade que contou com a participa\u00e7\u00e3o de milhares de fi\u00e9is, missa presidida por Frei Glauber e uma missa solene em honra a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Missa-Solene-Dom-Vasconcelos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Missa-Solene-Dom-Vasconcelos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Missa-Solene-Dom-Vasconcelos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Missa-Solene-Dom-Vasconcelos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":21239,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-2\/","url_meta":{"origin":35834,"position":3},"title":"Aparecida nas \u00e1guas","author":"","date":"Outubro 10, 2022","format":false,"excerpt":"No pr\u00f3ximo dia 12, feriado nacional, a Igreja do Brasil celebra a festa da Rainha e Padroeira desta na\u00e7\u00e3o, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":31055,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-4\/","url_meta":{"origin":35834,"position":4},"title":"Aparecida nas \u00e1guas","author":"adminredacao","date":"Outubro 21, 2024","format":false,"excerpt":"Neste s\u00e1bado, dia 12, feriado nacional, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais uma vez, colocava-se ao\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":35832,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-5\/","url_meta":{"origin":35834,"position":5},"title":"Aparecida nas \u00e1guas","author":"adminredacao","date":"Outubro 13, 2025","format":false,"excerpt":"Neste domingo, dia 12, celebramos a festa da Rainha e Padroeira do Brasil, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais uma vez, colocava-se ao lado dos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=35834"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35834\/revisions"}],"predecessor-version":[{"id":35835,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/35834\/revisions\/35835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7687"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=35834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=35834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=35834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}