{"id":36940,"date":"2026-01-06T14:29:00","date_gmt":"2026-01-06T17:29:00","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=36940"},"modified":"2026-01-06T14:29:00","modified_gmt":"2026-01-06T17:29:00","slug":"entenda-mudancas-na-aposentadoria-em-2026","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/entenda-mudancas-na-aposentadoria-em-2026\/","title":{"rendered":"Entenda mudan\u00e7as na aposentadoria em 2026"},"content":{"rendered":"<p><strong>Reforma da Previd\u00eancia estabelece regras autom\u00e1ticas de transi\u00e7\u00e3o<\/strong><\/p>\n<p>POR Wellton M\u00e1ximo &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<br \/>\nQuem est\u00e1 prestes a se aposentar precisa estar atento. A reforma da Previd\u00eancia, promulgada em 2019, estabeleceu regras autom\u00e1ticas de transi\u00e7\u00e3o, que mudam a concess\u00e3o de benef\u00edcios a cada ano.<br \/>\nA pontua\u00e7\u00e3o para a aposentadoria por tempo de contribui\u00e7\u00e3o e por idade sofreu altera\u00e7\u00f5es.\u00a0Confira abaixo as mudan\u00e7as que come\u00e7am a vigorar neste ano.<br \/>\nAposentadoria por tempo de contribui\u00e7\u00e3o<br \/>\nA reforma da Previd\u00eancia estabeleceu quatro regras de transi\u00e7\u00e3o, das quais duas previram modifica\u00e7\u00f5es na virada de 2025 para 2026.\u00a0Na primeira regra, que estabelece um cronograma de transi\u00e7\u00e3o para a regra 86\/96, a pontua\u00e7\u00e3o composta pela soma da idade e dos anos de contribui\u00e7\u00e3o subiu em janeiro: para 93 pontos (mulheres) e 103 pontos (homens).<br \/>\nOs servidores p\u00fablicos est\u00e3o submetidos \u00e0 mesma regra de pontua\u00e7\u00e3o, com a diferen\u00e7a de que \u00e9 necess\u00e1rio ter 62 anos de idade e 35 anos de contribui\u00e7\u00e3o (homens), 57 anos de idade e 30 anos (mulheres). Para ambos os sexos, \u00e9 necess\u00e1rio ter 20 anos no servi\u00e7o p\u00fablico e cinco anos no cargo.<br \/>\nNa segunda regra, que prev\u00ea idade m\u00ednima mais baixa para quem tem longo tempo de contribui\u00e7\u00e3o, a idade m\u00ednima para requerer o benef\u00edcio passou para 59 anos e meio (mulheres) e 64 anos e meio (homens). A reforma da Previd\u00eancia acrescenta seis meses \u00e0s idades m\u00ednimas a cada ano at\u00e9 atingirem 62 anos (mulheres) e 65 anos (homens) em 2031. Nos dois casos, o tempo m\u00ednimo de contribui\u00e7\u00e3o exigido \u00e9 de 30 anos para as mulheres e 35 anos para homens.<\/p>\n<p>Professores<br \/>\nEm rela\u00e7\u00e3o aos professores,\u00a0que obedecem a uma regra de transi\u00e7\u00e3o com base no tempo de contribui\u00e7\u00e3o na fun\u00e7\u00e3o de magist\u00e9rio combinada com a idade m\u00ednima,\u00a0as mulheres passam a se aposentar aos 54 anos e meio,\u00a0e os homens, aos 59 anos e meio.\u00a0A idade \u00e9 acrescida seis meses a cada ano at\u00e9 atingir o limite de 57 anos para mulheres e 60 anos para homens, em 2031. O tempo de contribui\u00e7\u00e3o m\u00ednimo para obter a aposentadoria como professor corresponde a 25 anos para as mulheres e a 30 anos para os homens.\u00a0A regra vale para os professores da iniciativa privada, das institui\u00e7\u00f5es federais de ensino e de pequenos munic\u00edpios. Os professores estaduais e de grandes munic\u00edpios obedecem \u00e0s regras dos regimes pr\u00f3prios de previd\u00eancia.<\/p>\n<p>Aposentadoria por idade<br \/>\nDesde 2023, est\u00e1 plenamente em vigor a regra para a aposentadoria por idade, destinada a trabalhadores de baixa renda que contribu\u00edram pouco para a Previd\u00eancia Social e se aposentariam por idade na regra antiga.<br \/>\nPara homens, a idade m\u00ednima est\u00e1 fixada em 65 anos desde 2019. Para as mulheres, a idade de transi\u00e7\u00e3o est\u00e1 em 62 anos desde 2023.\u00a0Para ambos os sexos,\u00a0o tempo m\u00ednimo de contribui\u00e7\u00e3o exigido para se aposentar por idade est\u00e1 em 15 anos.<br \/>\nNa promulga\u00e7\u00e3o da reforma da Previd\u00eancia, em novembro de 2019, a idade m\u00ednima para as mulheres estava em 60 anos, passando a aumentar seis meses por ano nos quatro anos seguintes. Subiu para 60 anos e meio em janeiro de 2020, para 61 anos em janeiro de 2021, 61 anos e meio em 2022 e 62 anos em 2023.<\/p>\n<p>Simula\u00e7\u00f5es<br \/>\nO Instituto Nacional do Seguro Social (INSS) permite simula\u00e7\u00f5es da aposentadoria no computador e no celular.<\/p>\n<p>Simula\u00e7\u00e3o no computador<br \/>\nEntre no\u00a0site\u00a0meu.inss.gov.br\u00a0e digite seu CPF e senha. Caso n\u00e3o tenha senha, cadastre uma;<br \/>\nV\u00e1 em \u201cServi\u00e7os\u201d e clique em \u201cSimular Aposentadoria\u201d;<br \/>\nConfira as informa\u00e7\u00f5es que aparecer\u00e3o na tela. O\u00a0site\u00a0vai mostrar sua idade, sexo e tempo de contribui\u00e7\u00e3o, al\u00e9m de quanto tempo falta para aposentadoria, segundo cada uma das regras em vigor.<\/p>\n<p>Simula\u00e7\u00e3o no celular<br \/>\nBaixe o aplicativo Meu INSS (dispon\u00edvel para Android e iOS);<br \/>\nSe necess\u00e1rio, clique no bot\u00e3o \u201cEntrar com gov.br\u201d e digite seu CPF e senha. Caso n\u00e3o tenha senha, cadastre uma;<br \/>\nAbra o menu lateral (na parte superior esquerda) e clique em \u201cSimular Aposentadoria\u201d;<br \/>\nCheque as informa\u00e7\u00f5es que aparecer\u00e3o na tela. O\u00a0site\u00a0vai mostrar sua idade, sexo e tempo de contribui\u00e7\u00e3o, al\u00e9m de quanto tempo falta para a aposentadoria, conforme as regras em vigor;<br \/>\nCaso precise corrigir algum dado pessoal basta clicar no \u00edcone de l\u00e1pis (\u00e0 direita).<br \/>\nO segurado pode salvar o documento com todos os dados das simula\u00e7\u00f5es. Basta clicar em \u201cBaixar PDF\u201d.<br \/>\nRegras de transi\u00e7\u00e3o j\u00e1 cumpridas<br \/>\nPor j\u00e1 ter sido cumprida, a regra do ped\u00e1gio de 100% sobre o tempo de contribui\u00e7\u00e3o n\u00e3o mudar\u00e1 no setor privado. Quem tem mais de 57 anos de idade e 30 anos de contribui\u00e7\u00e3o (mulheres) ou 60 anos de idade e 35 anos de contribui\u00e7\u00e3o (homens) pode se aposentar. A regra estabelecia que o segurado tinha de cumprir o dobro do per\u00edodo que faltava para se aposentar na promulga\u00e7\u00e3o da reforma, em 2019.<br \/>\nNo servi\u00e7o p\u00fablico, o ped\u00e1gio tamb\u00e9m foi cumprido. Al\u00e9m da idade e do tempo de contribui\u00e7\u00e3o m\u00ednimos exigidos dos trabalhadores da iniciativa privada, \u00e9 necess\u00e1rio ter 20 anos de servi\u00e7o p\u00fablico e cinco anos no cargo.<br \/>\nA reforma tinha outra regra de ped\u00e1gio, desta vez para o setor privado. Quem estava a at\u00e9 dois anos da aposentadoria em 2019 tinha de cumprir 50% a mais em rela\u00e7\u00e3o ao tempo que faltava para se aposentar. No entanto, essa regra de transi\u00e7\u00e3o foi integralmente cumprida e n\u00e3o beneficiar\u00e1 mais ningu\u00e9m em 2026.<br \/>\nNo cen\u00e1rio mais abrangente, quem trabalharia por mais dois anos em 2019 teve de trabalhar um ano extra, totalizando tr\u00eas anos. No fim de 2022, todos os que estavam enquadrados na regra do ped\u00e1gio de 50% j\u00e1 se aposentaram.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reforma da Previd\u00eancia estabelece regras autom\u00e1ticas de transi\u00e7\u00e3o POR Wellton M\u00e1ximo &#8211; Rep\u00f3rter da Ag\u00eancia&#8230;<\/p>\n","protected":false},"author":7,"featured_media":36941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-36940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875.webp",1170,700,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-150x150.webp",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-300x179.webp",300,179,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-768x459.webp",640,383,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-1024x613.webp",640,383,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875.webp",1170,700,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875.webp",1170,700,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-1024x613.webp",1024,613,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875-540x340.webp",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/0d9a5875.webp","jetpack-related-posts":[{"id":22783,"url":"https:\/\/correiodasemana.com\/site\/agencia-brasil-explica-as-mudancas-nas-aposentadorias-em-2023\/","url_meta":{"origin":36940,"position":0},"title":"Ag\u00eancia Brasil explica as mudan\u00e7as nas aposentadorias em 2023","author":"","date":"Janeiro 16, 2023","format":false,"excerpt":"Quem est\u00e1 prestes a se aposentar precisa ficar atento. A reforma da Previd\u00eancia estabeleceu regras autom\u00e1ticas de transi\u00e7\u00e3o, que mudam a concess\u00e3o de benef\u00edcios a cada ano. A pontua\u00e7\u00e3o para a aposentadoria por tempo de contribui\u00e7\u00e3o e por idade sofreu altera\u00e7\u00f5es. Confira abaixo as mudan\u00e7as que come\u00e7am a vigorar neste\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/inss_rj_1409201583.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/inss_rj_1409201583.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/inss_rj_1409201583.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/inss_rj_1409201583.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/inss_rj_1409201583.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8686,"url":"https:\/\/correiodasemana.com\/site\/reforma-da-previdencia-entenda-ponto-a-ponto-a-proposta-aprovada-pela-camara\/","url_meta":{"origin":36940,"position":1},"title":"Reforma da Previd\u00eancia: entenda ponto a ponto a proposta aprovada pela C\u00e2mara","author":"","date":"Agosto 17, 2019","format":false,"excerpt":"Veja como podem ficar as novas regras para as aposentadorias e pens\u00f5es. Deputados conclu\u00edram vota\u00e7\u00e3o em 1\u00ba e 2\u00ba turno, e agora proposta segue para o Senado. Por G1 A C\u00e2mara dos Deputados\u00a0concluiu nesta quarta-feira (7) a vota\u00e7\u00e3o em 2\u00ba turno da reforma da Previd\u00eancia. Os deputados rejeitaram todos os\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/vac_abr_0879230719.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/vac_abr_0879230719.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/vac_abr_0879230719.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/vac_abr_0879230719.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/vac_abr_0879230719.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9854,"url":"https:\/\/correiodasemana.com\/site\/saiba-como-fica-a-aposentadoria-com-as-novas-regras-aprovadas\/","url_meta":{"origin":36940,"position":2},"title":"Saiba como fica a aposentadoria com as novas regras aprovadas","author":"","date":"Novembro 18, 2019","format":false,"excerpt":"Fonte Ag\u00eancia Brasil As\u00a0novas regras para a aposentadoria\u00a0 j\u00e1 est\u00e3o valendo desde ter\u00e7a-feira (12). Com a promulga\u00e7\u00e3o da Nova Previd\u00eancia, marcada para \u00e0s 10h, em cerim\u00f4nia no Congresso Nacional, todas as mudan\u00e7as aprovadas na Emenda Constitucional entram em vigor. Segundo o\u00a0INSS (Instituto Nacional do Seguro Social), para a an\u00e1lise dos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/11\/img1-Como-fica-a-aposentadoria-para-quem-tem-21276.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":37045,"url":"https:\/\/correiodasemana.com\/site\/inss-novas-regras-da-aposentadoria-comecaram-a-valer-em-1o-de-janeiro\/","url_meta":{"origin":36940,"position":3},"title":"INSS: Novas regras da aposentadoria come\u00e7aram a valer em 1\u00ba de janeiro","author":"adminredacao","date":"Janeiro 17, 2026","format":false,"excerpt":"Atualiza\u00e7\u00f5es afetam quem j\u00e1 estava trabalhando antes da reforma de 2019; transi\u00e7\u00f5es exigem aten\u00e7\u00e3o a idade, tempo e pontos Por:\u00a0Katia Maia As\u00a0regras das aposentadorias pelo INSS mudaram mais uma vez. A partir de 1\u00ba de janeiro, entraram em vigor as novas faixas de transi\u00e7\u00e3o criadas ap\u00f3s a reforma da Previd\u00eancia,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/60d72ee5f4e29a2a7fafe1ea1db98d25.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/60d72ee5f4e29a2a7fafe1ea1db98d25.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/60d72ee5f4e29a2a7fafe1ea1db98d25.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/01\/60d72ee5f4e29a2a7fafe1ea1db98d25.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27919,"url":"https:\/\/correiodasemana.com\/site\/confira-as-novas-regras-para-aposentadoria-em-2024\/","url_meta":{"origin":36940,"position":4},"title":"Confira as novas regras para aposentadoria em 2024","author":"adminredacao","date":"Janeiro 5, 2024","format":false,"excerpt":"Transi\u00e7\u00e3o mant\u00e9m necessidade de tempo m\u00ednimo de contribui\u00e7\u00e3o Por Luiz Claudio Ferreira - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia Quem est\u00e1 contando os anos ou dias para se aposentar deve levar em conta como as novas regras aprovadas pela\u00a0Reforma da Previd\u00eancia\u00a0causam efeitos em 2024. S\u00e3o as regras de transi\u00e7\u00e3o que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/mcamg_abr_06092018_9648_1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/mcamg_abr_06092018_9648_1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/mcamg_abr_06092018_9648_1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/mcamg_abr_06092018_9648_1.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/mcamg_abr_06092018_9648_1.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":32226,"url":"https:\/\/correiodasemana.com\/site\/saiba-idade-minima-e-tempo-de-contribuicao-para-aposentadoria-em-2025\/","url_meta":{"origin":36940,"position":5},"title":"Saiba idade m\u00ednima e tempo de contribui\u00e7\u00e3o para aposentadoria em 2025","author":"adminredacao","date":"Janeiro 16, 2025","format":false,"excerpt":"Faixa et\u00e1ria vai aumentando seis meses a cada ano Luiz Claudio Ferreira - Rep\u00f3rter da Ag\u00eancia Brasil Para saber quando ser\u00e1 o momento de se aposentar, o trabalhador precisa estar atento \u00e0s regras estipuladas pela Reforma da Previd\u00eancia aprovada em 2019. Para a aposentadoria por tempo de contribui\u00e7\u00e3o, a idade\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/inss-endereco-novo-4-800x600-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/inss-endereco-novo-4-800x600-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/inss-endereco-novo-4-800x600-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/inss-endereco-novo-4-800x600-1.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/36940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=36940"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/36940\/revisions"}],"predecessor-version":[{"id":36942,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/36940\/revisions\/36942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/36941"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=36940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=36940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=36940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}