{"id":38308,"date":"2026-05-12T23:27:24","date_gmt":"2026-05-13T02:27:24","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=38308"},"modified":"2026-05-12T23:27:24","modified_gmt":"2026-05-13T02:27:24","slug":"em-tempo-324","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-324\/","title":{"rendered":"Em tempo"},"content":{"rendered":"<p><strong>Centen\u00e1rio do artista pl\u00e1stico Z\u00e9 Pinto<\/strong><br \/>\n4\u00aa edi\u00e7\u00e3o da Mostra Fazendo Artes, Aprendendo Of\u00edcios, em homenagem ao centen\u00e1rio do nascimento do artista pl\u00e1stico Z\u00e9 Pinto, em Fortaleza, prossegue 15 de maio, na Escola de Artes e Of\u00edcios Thomaz Pompeu Sobrinho, com trabalhos de alunos no ciclo formativo 2025\/26. S\u00e3o obras no campo dos of\u00edcios tradicionais (Bordado, Gravura e Prataria Artesanal) e na \u00e1rea da Conserva\u00e7\u00e3o e Restaura\u00e7\u00e3o de bens patrimoniais. A Mostra conta tamb\u00e9m com 13 esculturas do Z\u00e9 Pinto, que era o nome art\u00edstico de Francisco Magalh\u00e3es Barbosa (1925-2004).<\/p>\n<p><strong>Ednardo comemora 81 anos com show<\/strong><br \/>\nO cantor e compositor cearense Ednardo subiu ao palco para momento especial de sua trajet\u00f3ria. Em 17 de abril, data em que completou 81 anos, o artista realizou o pr\u00e9-lan\u00e7amento do novo disco \u201cEdnardo | Hum Ano\u201d, em um pocket show gratuito no Iate Clube de Fortaleza.<br \/>\nCom mais de cinco d\u00e9cadas de carreira, Ednardo reuniu no show um recorte afetivo e autoral de sua obra. Com participa\u00e7\u00f5es artistas convidados, ele apresentou seis can\u00e7\u00f5es in\u00e9ditas e cl\u00e1ssicos que marcaram gera\u00e7\u00f5es como \u201cTerral\u201d, \u201cPav\u00e3o Mysteriozo\u201d e \u201cA Manga Rosa\u201d.<\/p>\n<p><strong>Livro \u201cA Cabe\u00e7a do Santo\u201d no carnaval<\/strong><br \/>\n<strong>Foto: Divulga\u00e7\u00e3o<\/strong><br \/>\n<strong><a href=\"https:\/\/correiodasemana.com\/site\/em-tempo-324\/socorro-acioli\/\" rel=\"attachment wp-att-38309\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-38309\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/Socorro-Acioli.jpg\" alt=\"\" width=\"1040\" height=\"780\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/Socorro-Acioli.jpg 1040w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/Socorro-Acioli-300x225.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/Socorro-Acioli-1024x768.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/Socorro-Acioli-768x576.jpg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/a>Jornalista, professora universit\u00e1ria e escritora cearense Socorro Acioli<\/strong><br \/>\nO livro \u201cA Cabe\u00e7a do Santo\u201d, da escritora cearense Socorro Acioli, sucesso absoluto com o p\u00fablico e a cr\u00edtica, \u00e9 o tema escolhido para o samba-enredo do Carnaval de 2027 pela Escola de Samba Unidos da Tijuca, agremia\u00e7\u00e3o sediada no Morro do Borel, no Rio de Janeiro.<br \/>\nO ponto de partida do romance surgiu de hist\u00f3ria real em Caridade, no Sert\u00e3o Central do Cear\u00e1. Na d\u00e9cada de 1980, uma grande imagem de Santo Ant\u00f4nio come\u00e7ou a ser constru\u00edda no alto de um morro, mas n\u00e3o foi conclu\u00edda e a cabe\u00e7a ficou separada do restante da escultura.<\/p>\n<p><strong>\u201cGrande Sert\u00e3o: Veredas\u201d em \u00e1udio<\/strong><br \/>\nSetenta anos ap\u00f3s sua publica\u00e7\u00e3o, \u201cGrande Sert\u00e3o: Veredas\u201d \u00e9 uma travessia que exige entrega, e agora tamb\u00e9m de quem escuta. Neste contexto, a Companhia das Letras lan\u00e7ou edi\u00e7\u00e3o comemorativa em audiobook do cl\u00e1ssico de Jo\u00e3o Guimar\u00e3es Rosa, com o ator Caio Blat.<br \/>\nO livro que tensionou os limites da l\u00edngua e fez do sert\u00e3o mineiro um territ\u00f3rio ao mesmo tempo concreto e metaf\u00edsico, ganha nova inflex\u00e3o. A edi\u00e7\u00e3o em \u00e1udio \u00e9 acompanhada por uma trilha discreta e pela viola de Ivan Vilela. Onde encontrar: www.audible.com.br.<\/p>\n<p><strong>UVA oferta 1.114 vagas no Vestibular<\/strong><br \/>\nUniversidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es, at\u00e9 o dia 5 de maio, para o Vestibular 2026.2. Est\u00e3o sendo ofertadas 1.114 vagas para diversos cursos de gradua\u00e7\u00e3o, sendo 834 vagas em Sobral, 80 em Acara\u00fa, 80 em Camocim e 120 no campus de S\u00e3o Benedito.<br \/>\nO processo seletivo utiliza o aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem) para o ingresso na UVA, incluindo vagas no novo curso de Psicologia. O Edital n\u00ba 08\/2026 est\u00e1 dispon\u00edvel para consulta no endere\u00e7o eletr\u00f4nico http:\/\/vestibular.uvanet.br.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br): Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centen\u00e1rio do artista pl\u00e1stico Z\u00e9 Pinto 4\u00aa edi\u00e7\u00e3o da Mostra Fazendo Artes, Aprendendo Of\u00edcios, em&#8230;<\/p>\n","protected":false},"author":7,"featured_media":18025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-38308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg","jetpack-related-posts":[{"id":33317,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-272\/","url_meta":{"origin":38308,"position":0},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 14, 2025","format":false,"excerpt":"Inscri\u00e7\u00f5es para o Vestibular UVA 2025.2 A Universidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es at\u00e9 o dia 6 de maio para Vestibular 2025.2, com aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem). Ser\u00e3o aceitas as pontua\u00e7\u00f5es das dez \u00faltimas edi\u00e7\u00f5es, realizadas entre 2015 e 2024. S\u00e3o ofertadas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Nonato-Costa-150x150.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28992,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-223\/","url_meta":{"origin":38308,"position":1},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 22, 2024","format":false,"excerpt":"UFC seleciona professor substituto A Universidade Federal do Cear\u00e1 publicou edital para sele\u00e7\u00e3o de professor substituto em diferentes unidades de Fortaleza e nos campi de Itapaj\u00e9, Sobral e Crate\u00fas, em \u00e1reas de estudo diversas. Ao todo, s\u00e3o ofertadas 18 vagas. As inscri\u00e7\u00f5es ser\u00e3o abertas a partir do dia 24 de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Ednardo-thiago-gadelha-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Ednardo-thiago-gadelha-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Ednardo-thiago-gadelha-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Ednardo-thiago-gadelha-150x150.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Ednardo-thiago-gadelha-150x150.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19257,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-125\/","url_meta":{"origin":38308,"position":2},"title":"Em Tempo","author":"","date":"Mar\u00e7o 20, 2022","format":false,"excerpt":"Ednardo recebe homenagem No ano de 2022, um dos maiores nomes da m\u00fasica cearense completa 50 anos de carreira, o cantor e compositor Ednardo. Respons\u00e1vel por sucessos como Pav\u00e3o Mysteriozo, Terral, Beiramar e Ingazeiras, o artista ganhou uma homenagem do Sistema Fecom\u00e9rcio Cear\u00e1. Em forma de document\u00e1rio, lan\u00e7ado durante a\u00a0Mostra\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/TS-300x169.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":33206,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-271\/","url_meta":{"origin":38308,"position":3},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 7, 2025","format":false,"excerpt":"Bienal Internacional do Livro do Cear\u00e1 Entre 4 e 13 de abril, a XV Bienal Internacional do Livro do Cear\u00e1 conta com cortejos, palestras, oficinas, apresenta\u00e7\u00f5es com artistas e lan\u00e7amentos de livros. Programa\u00e7\u00e3o ocorre em Fortaleza com o tema \u201cDas fogueiras ao fogo das palavras: mulheres, resist\u00eancia e literatura\u201d. Dez\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/eDILSON-sILVA-1_ednardo_credito_ceara_filmes_-150x150.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/eDILSON-sILVA-1_ednardo_credito_ceara_filmes_-150x150.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/eDILSON-sILVA-1_ednardo_credito_ceara_filmes_-150x150.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/eDILSON-sILVA-1_ednardo_credito_ceara_filmes_-150x150.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19619,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-130\/","url_meta":{"origin":38308,"position":4},"title":"Em Tempo","author":"","date":"Abril 24, 2022","format":false,"excerpt":"Pr\u00eamio Sesc de Artes C\u00eanicas O Pr\u00eamio Sesc de Artes C\u00eanicas recebe propostas de espet\u00e1culos at\u00e9 o dia 8 de maio, com inscri\u00e7\u00f5es de projetos in\u00e9ditos de teatro, dan\u00e7a, circo e outras modalidades. Cinco propostas ser\u00e3o contempladas: uma receber\u00e1 R$100 mil, duas ganhar\u00e3o R$70 mil e outras duas ter\u00e3o R$50\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/cantor-fortaleza-300x275.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19309,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-126\/","url_meta":{"origin":38308,"position":5},"title":"Em Tempo","author":"","date":"Mar\u00e7o 27, 2022","format":false,"excerpt":"Inscri\u00e7\u00f5es para o Edital Cultura Viva A\u00a0Secretaria da Cultura do Estado do Cear\u00e1\u00a0(Secult\/CE) abriu inscri\u00e7\u00f5es gratuitas para o\u00a0Edital Cultura Viva 2022. Os interessados podem se inscrever at\u00e9 \u00e0s 23h59min do pr\u00f3ximo dia 15 de abril. As inscri\u00e7\u00f5es s\u00e3o exclusivamente on-line, no site http:\/\/editais.cultura.ce.gov.br Para potencializar iniciativas j\u00e1 desenvolvidas, articular e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/19-01-2021-lcio-Batista-300x203.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=38308"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38308\/revisions"}],"predecessor-version":[{"id":38311,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38308\/revisions\/38311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18025"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=38308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=38308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=38308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}