{"id":38344,"date":"2026-05-12T23:38:10","date_gmt":"2026-05-13T02:38:10","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=38344"},"modified":"2026-05-12T23:38:10","modified_gmt":"2026-05-13T02:38:10","slug":"entenda-o-novo-desenrola-brasil-lancado-hoje-pelo-governo-federal","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/entenda-o-novo-desenrola-brasil-lancado-hoje-pelo-governo-federal\/","title":{"rendered":"Entenda o novo Desenrola Brasil, lan\u00e7ado hoje pelo governo federal"},"content":{"rendered":"<p><strong><em>Nova fase ter\u00e1 dura\u00e7\u00e3o de 90 dias e prev\u00ea descontos de at\u00e9 90%<\/em><\/strong><\/p>\n<p>POR Pedro Peduzzi &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<\/p>\n<p>O governo federal lan\u00e7ou nesta segunda-feira (4) o\u00a0Novo Desenrola Brasil, programa que busca ajudar fam\u00edlias, estudantes e pequenos empreendedores a renegociar d\u00edvidas, limpar o nome e recuperar o acesso ao cr\u00e9dito.<br \/>\nA nova fase da iniciativa ter\u00e1 dura\u00e7\u00e3o de 90 dias e prev\u00ea descontos de at\u00e9 90%, juros reduzidos e a possibilidade de uso do FGTS para abatimento de d\u00e9bitos.<br \/>\nFormalizada com a assinatura de uma medida provis\u00f3ria pelo presidente Luiz In\u00e1cio Lula da Silva, a estrat\u00e9gia visa promover a reorganiza\u00e7\u00e3o financeira de milh\u00f5es de brasileiros e\u00a0ampliar o acesso ao cr\u00e9dito em condi\u00e7\u00f5es mais favor\u00e1veis.<br \/>\nDurante a cerim\u00f4nia no Pal\u00e1cio do Planalto,\u00a0o presidente Lula afirmou que a\u00a0iniciativa busca aliviar o peso das d\u00edvidas\u00a0e permitir que as pessoas voltem a respirar financeiramente, destacando que n\u00e3o \u00e9 razo\u00e1vel que restri\u00e7\u00f5es de cr\u00e9dito ocorram por d\u00e9bitos de baixo valor.<br \/>\nJ\u00e1 o ministro da Fazenda, Dario Durigan, explicou que a ideia do governo \u00e9 criar mecanismos estruturantes para melhores condi\u00e7\u00f5es de pagamentos a novas d\u00edvidas que venham a ser contra\u00eddas. \u201cA gente precisa recuperar a qualidade do cr\u00e9dito que essa pessoa toma\u201d, disse.<br \/>\n\u201cO mais importante\u00a0para as fam\u00edlias\u00a0\u00e9 que a pessoa que est\u00e1 endividada e precisa dessa ajuda contar\u00e1 com um fundo garantidor do Poder P\u00fablico\u201d, acrescentou.<br \/>\nNovo Desenrola<br \/>\nMobiliza\u00e7\u00e3o\u00a0nacional com dura\u00e7\u00e3o de 90 dias<br \/>\nFoco na renegocia\u00e7\u00e3o de d\u00edvidas de fam\u00edlias; estudantes; agricultores familiares; aposentados e pensionistas; micro e pequenas empresas<br \/>\nPrevis\u00e3o de grandes descontos, juros menores e uso de garantias p\u00fablicas<br \/>\nObjetivo de reduzir a inadimpl\u00eancia e estimular o uso consciente do cr\u00e9dito<br \/>\nPrincipais frentes<br \/>\n1) Desenrola Fam\u00edlias<br \/>\nVoltado \u00e0 renegocia\u00e7\u00e3o de d\u00edvidas de pessoas f\u00edsicas<br \/>\nPodem participar pessoas com renda de at\u00e9 5 sal\u00e1rios m\u00ednimos (R$ 8.105)<br \/>\nD\u00edvidas podem ser renegociadas: contratadas at\u00e9 31 de janeiro de 2026, com atraso entre 90 dias e dois anos, nas modalidades cart\u00e3o de cr\u00e9dito, cheque especial e cr\u00e9dito pessoal n\u00e3o consignado<br \/>\nCondi\u00e7\u00f5es da renegocia\u00e7\u00e3o<br \/>\nDescontos entre 30% e 90%, com juros de at\u00e9 1,99% ao m\u00eas e prazo de pagamento de at\u00e9 48 meses<br \/>\nIn\u00edcio do pagamento em at\u00e9 30 dias<br \/>\nParcelas m\u00ednimas de R$ 50<br \/>\nLimite de at\u00e9 R$ 15 mil por pessoa, por institui\u00e7\u00e3o financeira<br \/>\nNovidades<br \/>\nPossibilidade de uso de 20% do saldo do FGTS ou at\u00e9 R$ 1 mil, o que for maior, ap\u00f3s a renegocia\u00e7\u00e3o<br \/>\nContrapartidas<br \/>\nBloqueio do CPF por 12 meses para apostas online<br \/>\nBancos devem investir 1% das garantias do programa em educa\u00e7\u00e3o financeira<br \/>\nContinuidade da proibi\u00e7\u00e3o de envio de recursos para apostas por meio de cr\u00e9dito<br \/>\nPrincipais altera\u00e7\u00f5es no cr\u00e9dito consignado:<br \/>\nFim da reserva obrigat\u00f3ria de 10% para cart\u00e3o consignado e de benef\u00edcios<br \/>\nMargem total cai de 45% para 40%<br \/>\nLimite de at\u00e9 5% para cart\u00f5es consignados<br \/>\nPrazo m\u00e1ximo ser\u00e1 de 108 meses no caso dos benefici\u00e1rios do INSS; e de at\u00e9 120 meses para servidores federais<br \/>\nCar\u00eancia de at\u00e9 3 meses<br \/>\nRedu\u00e7\u00e3o gradual das margens a partir de 2027<br \/>\n2) Desenrola Fies<br \/>\nRenegocia\u00e7\u00e3o de d\u00edvidas estudantis, com condi\u00e7\u00f5es conforme o atraso e o perfil do estudante.<br \/>\nD\u00edvidas entre 90 e 360 dias ter\u00e3o desconto de 100% dos juros e multas; pagamento \u00e0 vista inclui desconto adicional de 12% do principal; possibilidade de parcelamento em at\u00e9 150 vezes<br \/>\nD\u00edvidas acima de 360 dias: desconto de at\u00e9 77% para estudantes fora do Cad\u00danico; descontos de at\u00e9 99% para estudantes do Cad\u00danico<br \/>\nExpectativa de beneficiar mais de 1 milh\u00e3o de estudantes<br \/>\n3) Desenrola Empresas<br \/>\nVoltado a micro e pequenas empresas, com foco na substitui\u00e7\u00e3o de d\u00edvidas caras por cr\u00e9dito com melhores condi\u00e7\u00f5es. A expectativa \u00e9 a de alcan\u00e7ar mais de 2 milh\u00f5es de empresas, com melhoria das linhas do ProCred e do Pronampe<br \/>\nMicroempresas (at\u00e9 R$ 360 mil\/ano) ter\u00e3o a car\u00eancia sendo ampliada de 12 para 24 meses. O prazo total passou de 72 para 96 meses; e a toler\u00e2ncia \u00e0 inadimpl\u00eancia passou de 14 para 90 dias<br \/>\nCr\u00e9dito de at\u00e9 50% do faturamento, chegando a 60% para empresas lideradas por mulheres<br \/>\nEmpresas com receitas de at\u00e9 R$ 4,8 milh\u00f5es\/ano ter\u00e3o car\u00eancia de at\u00e9 24 meses; prazo de at\u00e9 96 meses; e limite de cr\u00e9dito sobe de R$ 250 mil para R$ 500 mil<br \/>\n4) Desenrola Rural<br \/>\nRelan\u00e7ado para atender agricultores familiares, visando a regulariza\u00e7\u00e3o de d\u00edvidas antigas; a amplia\u00e7\u00e3o do prazo para renegocia\u00e7\u00e3o at\u00e9 20 de dezembro de 2026; e a facilita\u00e7\u00e3o do acesso ao cr\u00e9dito rural e retomada da capacidade produtiva<br \/>\nExpectativa de que o programa atenda cerca de 1,3 milh\u00e3o de agricultores familiares<br \/>\nDura\u00e7\u00e3o do programa<br \/>\nO Novo Desenrola Brasil ter\u00e1 validade de 90 dias<br \/>\nD\u00edvidas de at\u00e9 R$ 100, quitadas nos moldes do programa, resultar\u00e3o em nome limpo imediato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova fase ter\u00e1 dura\u00e7\u00e3o de 90 dias e prev\u00ea descontos de at\u00e9 90% POR Pedro&#8230;<\/p>\n","protected":false},"author":7,"featured_media":38345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-38344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/desenrola.webp","jetpack-related-posts":[{"id":25176,"url":"https:\/\/correiodasemana.com\/site\/dividas-de-ate-r-5-mil-poderao-ser-parceladas-em-60-meses\/","url_meta":{"origin":38344,"position":0},"title":"D\u00edvidas de at\u00e9 R$ 5 mil poder\u00e3o ser parceladas em 60 meses","author":"adminredacao","date":"Junho 12, 2023","format":false,"excerpt":"Programa de renegocia\u00e7\u00e3o deve reduzir inadimpl\u00eancia no pa\u00eds Por Alex Rodrigues - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O governo federal publicou no\u00a0Di\u00e1rio Oficial da Uni\u00e3o\u00a0desta ter\u00e7a-feira (6) medida provis\u00f3ria que lan\u00e7a o Programa Emergencial de Renegocia\u00e7\u00e3o de D\u00edvidas de Pessoas F\u00edsicas Inadimplentes, o chamado Desenrola Brasil. Primeira das tr\u00eas\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/real_moedadinheiro_jfcrz_abr_1701220049_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/real_moedadinheiro_jfcrz_abr_1701220049_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/real_moedadinheiro_jfcrz_abr_1701220049_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/real_moedadinheiro_jfcrz_abr_1701220049_1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/real_moedadinheiro_jfcrz_abr_1701220049_1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25724,"url":"https:\/\/correiodasemana.com\/site\/desenrola-brasil-renegociacao-de-dividas-da-faixa-2-comeca-na-segunda\/","url_meta":{"origin":38344,"position":1},"title":"Desenrola Brasil: renegocia\u00e7\u00e3o de d\u00edvidas da Faixa 2 come\u00e7a na segunda","author":"adminredacao","date":"Julho 17, 2023","format":false,"excerpt":"Esta etapa atende brasileiros com renda de R$ 2,6 mil at\u00e9 R$ 20 mil Por Fab\u00edola Sinimb\u00fa \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O Minist\u00e9rio da Fazenda autorizou\u00a0nesta sexta-feira (14) que\u00a0as institui\u00e7\u00f5es financeiras credenciadas pelo Banco Central (BC) para opera\u00e7\u00f5es de cr\u00e9dito podem come\u00e7ar, a partir de segunda-feira (17),\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/dinheiro_caixa_mcajr_abr_2907221125.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/dinheiro_caixa_mcajr_abr_2907221125.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/dinheiro_caixa_mcajr_abr_2907221125.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/dinheiro_caixa_mcajr_abr_2907221125.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/dinheiro_caixa_mcajr_abr_2907221125.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16310,"url":"https:\/\/correiodasemana.com\/site\/camara-aprova-medida-sobre-renegociacao-de-dividas-de-empresas\/","url_meta":{"origin":38344,"position":2},"title":"C\u00e2mara aprova medida sobre renegocia\u00e7\u00e3o de d\u00edvidas de empresas","author":"","date":"Maio 2, 2021","format":false,"excerpt":"MP permite descontos na quita\u00e7\u00e3o de d\u00e9bitos com fundos constitucionais Por Luciano Nascimento \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia A C\u00e2mara dos Deputados concluiu a vota\u00e7\u00e3o da Medida Provis\u00f3ria (MP) 1.016\/20, que prev\u00ea renegocia\u00e7\u00e3o extraordin\u00e1ria de d\u00edvidas junto a fundos constitucionais do Nordeste, do Norte e do Centro-Oeste (FNE,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/monumentos_brasilia_cupula_plenario_da_camara_dos_deputados3103201341.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/monumentos_brasilia_cupula_plenario_da_camara_dos_deputados3103201341.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/monumentos_brasilia_cupula_plenario_da_camara_dos_deputados3103201341.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/monumentos_brasilia_cupula_plenario_da_camara_dos_deputados3103201341.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/monumentos_brasilia_cupula_plenario_da_camara_dos_deputados3103201341.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":32957,"url":"https:\/\/correiodasemana.com\/site\/saiba-como-vai-funcionar-o-credito-consignado-clt\/","url_meta":{"origin":38344,"position":3},"title":"Saiba como vai funcionar o cr\u00e9dito consignado CLT","author":"adminredacao","date":"Mar\u00e7o 17, 2025","format":false,"excerpt":"Programa lan\u00e7ado pelo governo come\u00e7a em 21 de mar\u00e7o O governo federal\u00a0lan\u00e7ou nesta quarta-feira (12) o Programa Cr\u00e9dito do Trabalhador na Carteira Digital de Trabalho, que promete facilitar e baratear os juros do empr\u00e9stimo consignado a trabalhadores registrados com carteira assinada (CLT). Assinada pelo presidente Luiz In\u00e1cio Lula da Silva,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/54382764540_68080a0da7_o.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/54382764540_68080a0da7_o.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/54382764540_68080a0da7_o.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/54382764540_68080a0da7_o.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/03\/54382764540_68080a0da7_o.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":27861,"url":"https:\/\/correiodasemana.com\/site\/congresso-nacional-aprova-projeto-da-lei-orcamentaria-para-2024\/","url_meta":{"origin":38344,"position":4},"title":"Congresso Nacional aprova projeto da lei or\u00e7ament\u00e1ria para 2024","author":"adminredacao","date":"Dezembro 26, 2023","format":false,"excerpt":"Mat\u00e9ria segue para san\u00e7\u00e3o do Presidente Lula Por Luciano Nascimento - Rep\u00f3rter da Ag\u00eancia Brasil - S\u00e3o Lu\u00eds O Congresso Nacional aprovou nesta sexta-feira (22) o projeto da lei or\u00e7ament\u00e1ria para 2024. O projeto (PLOA) 2024, prev\u00ea despesas de R$ 5,5 trilh\u00f5es. A maior parte \u00e9 para o refinanciamento da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/lula6834-2.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/lula6834-2.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/lula6834-2.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/lula6834-2.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/lula6834-2.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15782,"url":"https:\/\/correiodasemana.com\/site\/sobral-e-outros-municipios-cearenses-buscam-alternativas-para-suprir-a-suspensao-temporaria-do-auxilio-emergencial\/","url_meta":{"origin":38344,"position":5},"title":"Sobral e outros munic\u00edpios cearenses buscam alternativas para suprir a suspens\u00e3o tempor\u00e1ria do Aux\u00edlio Emergencial","author":"","date":"Fevereiro 24, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana O novo aux\u00edlio emergencial ainda segue em discuss\u00e3o no Congresso Nacional, enquanto isso, munic\u00edpios do estado do Cear\u00e1 tentam criar alternativas para garantir assist\u00eancia econ\u00f4mica para a popula\u00e7\u00e3o diante das incertezas de como ir\u00e1 acontecer as novas parcelas do programa. Em Sobral,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/unnamed.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=38344"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38344\/revisions"}],"predecessor-version":[{"id":38346,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38344\/revisions\/38346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/38345"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=38344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=38344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=38344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}