{"id":38350,"date":"2026-05-12T23:41:45","date_gmt":"2026-05-13T02:41:45","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=38350"},"modified":"2026-05-12T23:41:45","modified_gmt":"2026-05-13T02:41:45","slug":"comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade\/","title":{"rendered":"Comiss\u00e3o Diocesana Sociotransformadora debate papel da Igreja na sociedade"},"content":{"rendered":"<p>Reuni\u00e3o ampliada realizada no \u00faltimo s\u00e1bado (26\/04), no audit\u00f3rio da Par\u00f3quia Nossa Senhora do Patroc\u00ednio, em Sobral, reuniu cerca de 50 lideran\u00e7as entre cl\u00e9rigos, religiosas e leigos para refletir sobre a rela\u00e7\u00e3o entre a a\u00e7\u00e3o da Igreja e as pol\u00edticas p\u00fablicas \u00e0 luz da Doutrina Social da Igreja.<br \/>\nO encontro teve como eixo central a forma\u00e7\u00e3o e o planejamento das a\u00e7\u00f5es sociopastorais, promovendo momentos de escuta, di\u00e1logo e constru\u00e7\u00e3o conjunta.<br \/>\nParticiparam do encontro o vig\u00e1rio geral e p\u00e1roco da Par\u00f3quia S\u00e3o Manuel de Marco, Monsenhor Nonato Timb\u00f3; o coordenador da Comiss\u00e3o e quase-p\u00e1roco da Quase-Par\u00f3quia de Nossa Senhora da Sa\u00fade, em Jord\u00e3o, Padre Assis Neto; al\u00e9m de outros cl\u00e9rigos, religiosas e leigos comprometidos com a miss\u00e3o social da Igreja.<br \/>\nO vig\u00e1rio geral, Monsenhor Nonato Timb\u00f3, ofereceu uma leitura cr\u00edtica sobre o cen\u00e1rio pol\u00edtico atual, convidando os participantes a refletirem sobre os desafios sociais presentes na realidade da comunidade.<br \/>\nNa ocasi\u00e3o, o fundador da Comunidade M\u00e3e da Divina Provid\u00eancia, Rob\u00e9rio Cavalcante, apresentou as a\u00e7\u00f5es mission\u00e1rias desenvolvidas na dimens\u00e3o social, destacando iniciativas voltadas \u00e0 dignidade humana, \u00e0 promo\u00e7\u00e3o da vida e ao cuidado com os mais vulner\u00e1veis.<br \/>\nContribuindo com o momento formativo, o vereador de Fortaleza, Jorge Pinheiro, refletiu sobre o tema central, ressaltando a responsabilidade dos crist\u00e3os diante da sociedade e das pol\u00edticas p\u00fablicas.<br \/>\nO encontro encerrou com um horizonte claro: a Diocese de Sobral n\u00e3o apenas quer falar sobre justi\u00e7a social, quer pratic\u00e1-la. A reuni\u00e3o marcou o in\u00edcio de uma caminhada organizada de anima\u00e7\u00e3o e articula\u00e7\u00e3o das a\u00e7\u00f5es sociais em todo o territ\u00f3rio diocesano, com o compromisso de que a f\u00e9 crist\u00e3 se traduza em presen\u00e7a concreta junto aos que mais precisam.<br \/>\nThais Helena &#8211; Jornalista &#8211; Jornal Correio da Semana<\/p>\n<p><a href=\"https:\/\/correiodasemana.com\/site\/comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade\/whatsapp-image-2026-05-04-at-08-44-42-1\/\" rel=\"attachment wp-att-38351\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-38351\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1.jpeg\" alt=\"\" width=\"1066\" height=\"1600\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1.jpeg 1066w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1-200x300.jpeg 200w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1-682x1024.jpeg 682w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1-768x1153.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1-1023x1536.jpeg 1023w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1-1024x1537.jpeg 1024w\" sizes=\"(max-width: 1066px) 100vw, 1066px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade\/whatsapp-image-2026-05-04-at-08-44-42\/\" rel=\"attachment wp-att-38352\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-38352\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42.jpeg\" alt=\"\" width=\"1280\" height=\"848\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-300x199.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-1024x678.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42-768x509.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade\/whatsapp-image-2026-05-04-at-08-44-43-1\/\" rel=\"attachment wp-att-38353\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-38353\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1-300x225.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1-1024x768.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/comissao-diocesana-sociotransformadora-debate-papel-da-igreja-na-sociedade\/whatsapp-image-2026-05-04-at-08-44-43\/\" rel=\"attachment wp-att-38354\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-38354\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-300x225.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-1024x768.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.43-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reuni\u00e3o ampliada realizada no \u00faltimo s\u00e1bado (26\/04), no audit\u00f3rio da Par\u00f3quia Nossa Senhora do Patroc\u00ednio,&#8230;<\/p>\n","protected":false},"author":7,"featured_media":38352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-38350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-04-at-08.44.42.jpeg","jetpack-related-posts":[{"id":28282,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-apresenta-a-paroquia-de-acarau-novo-paroco-e-vigario-paroquial\/","url_meta":{"origin":38350,"position":0},"title":"Dom Vasconcelos apresenta \u00e0 Par\u00f3quia de Acara\u00fa novo p\u00e1roco e vig\u00e1rio paroquial","author":"adminredacao","date":"Fevereiro 6, 2024","format":false,"excerpt":"Em solene celebra\u00e7\u00e3o eucar\u00edstica na Festa da Apresenta\u00e7\u00e3o do Senhor no templo, nesta sexta-feira, 02 de fevereiro, Dom Vasconcelos apresentou o novo p\u00e1roco, Pe. Jo\u00e3o Vasconcelos, e o vig\u00e1rio paroquial, Pe. Adalberto Menezes, \u00e0 comunidade paroquial de Acara\u00fa. Padre Jo\u00e3o Vasconcelos j\u00e1 fez parte da regi\u00e3o quando foi p\u00e1roco da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18400,"url":"https:\/\/correiodasemana.com\/site\/em-celebracao-solene-pe-nonato-timbo-de-paiva-recebe-titulo-de-monsenhor\/","url_meta":{"origin":38350,"position":1},"title":"Em celebra\u00e7\u00e3o solene, Pe. Nonato Timb\u00f3 de Paiva recebe t\u00edtulo de Monsenhor","author":"","date":"Dezembro 20, 2021","format":false,"excerpt":"Por Thais Helena (Reda\u00e7\u00e3o Jornal Correio da Semana) Na \u00faltima segunda-feira, 13, dia da virgem e m\u00e1rtir Santa Luzia, toda a comunidade paroquial da cidade de Marco\/CE esteve reunida no adro da Igreja Matriz de S\u00e3o Manuel para celebrar a solene liturgia, onde Dom Vasconcelos entregou o t\u00edtulo de Monsenhor\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/monsenhor-timbo-diocese-de-sobral-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/monsenhor-timbo-diocese-de-sobral-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/monsenhor-timbo-diocese-de-sobral-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/monsenhor-timbo-diocese-de-sobral-3.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18532,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-sobral-alegra-se-com-os-aniversarios-de-ordenacao-de-tres-sacerdotes\/","url_meta":{"origin":38350,"position":2},"title":"Diocese de Sobral alegra-se com os anivers\u00e1rios de ordena\u00e7\u00e3o de tr\u00eas sacerdotes","author":"","date":"Janeiro 10, 2022","format":false,"excerpt":"Por Thais Helena (Reda\u00e7\u00e3o Jornal Correio da Semana) Monsenhor Gon\u00e7alo de Pinho Gomes O segundo bispo da Diocese de Sobral, Dom Jo\u00e3o Jos\u00e9 da Mota, na festa da Epifania, em 06 de janeiro de 1963, conferiu a ordena\u00e7\u00e3o sacerdotal ao esperan\u00e7oso Revmo. Monsenhor Gon\u00e7alo de Pinho Gomes, em Poranga, sua\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/capa.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":30555,"url":"https:\/\/correiodasemana.com\/site\/simposio-vocacional-e-santa-missa-marcam-o-encerramento-do-mes-vocacional-em-sobral\/","url_meta":{"origin":38350,"position":3},"title":"Simp\u00f3sio Vocacional e Santa Missa marcam o Encerramento do M\u00eas Vocacional em Sobral","author":"adminredacao","date":"Setembro 2, 2024","format":false,"excerpt":"Diversas express\u00f5es vocacionais participaram no \u00faltimo final de semana do I Simp\u00f3sio Vocacional realizado pela Pastoral Vocacional Diocesana e Santa Missa de Encerramento do m\u00eas dedicado as voca\u00e7\u00f5es. Simp\u00f3sio Vocacional No raiar de s\u00e1bado, 24 de agosto, aconteceu o I Simp\u00f3sio Vocacional em \u00e2mbito diocesano no audit\u00f3rio do Centro de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-08-30-at-14.19.24.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-08-30-at-14.19.24.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-08-30-at-14.19.24.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-08-30-at-14.19.24.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-08-30-at-14.19.24.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28334,"url":"https:\/\/correiodasemana.com\/site\/padre-tome-assume-nova-missao-na-paroquia-de-senhora-santana-em-varjota\/","url_meta":{"origin":38350,"position":4},"title":"Padre Tom\u00e9 assume nova miss\u00e3o na Par\u00f3quia de Senhora Sant\u2019Ana em Varjota","author":"adminredacao","date":"Fevereiro 15, 2024","format":false,"excerpt":"No dia em que a Par\u00f3quia dedicada a av\u00f3 de Jesus, Senhora Sant\u2019Ana em Varjota, celebra dezesseis anos de ere\u00e7\u00e3o can\u00f4nica, em 09 de fevereiro, a comunidade paroquial acolheu o terceiro p\u00e1roco, Pe. Tom\u00e9 da Silva. Nos \u00faltimos sete anos, a comunidade paroquial esteve aos cuidados de Pe. Jac\u00f3 Sidarta.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-11-at-12.43.56.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-11-at-12.43.56.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-11-at-12.43.56.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-11-at-12.43.56.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-11-at-12.43.56.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":34094,"url":"https:\/\/correiodasemana.com\/site\/conser-reune-clerigos-e-leigos-em-fortaleza\/","url_meta":{"origin":38350,"position":5},"title":"CONSER re\u00fane cl\u00e9rigos e leigos em Fortaleza","author":"adminredacao","date":"Junho 9, 2025","format":false,"excerpt":"Os bispos das nove dioceses do Cear\u00e1, incluindo o arcebispo de Fortaleza, participaram do Conselho Episcopal Regional (CONSER), realizado na Casa de Retiro S\u00e3o Jos\u00e9, na capital cearense, nos dias 2 e 3 de junho. Dom Vasconcelos, vice-presidente do Regional Nordeste 1 e bispo da Diocese de Sobral, esteve presente\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=38350"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38350\/revisions"}],"predecessor-version":[{"id":38356,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/38350\/revisions\/38356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/38352"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=38350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=38350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=38350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}