{"id":39187,"date":"2026-07-14T18:48:23","date_gmt":"2026-07-14T21:48:23","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=39187"},"modified":"2026-07-14T18:48:35","modified_gmt":"2026-07-14T21:48:35","slug":"temor-de-fraudes-com-inteligencia-artificial-atinge-88-da-populacao-da-regiao","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/temor-de-fraudes-com-inteligencia-artificial-atinge-88-da-populacao-da-regiao\/","title":{"rendered":"Temor de fraudes com intelig\u00eancia artificial atinge 88% da popula\u00e7\u00e3o da regi\u00e3o"},"content":{"rendered":"<p>Pesquisa Observat\u00f3rio Febraban mostra que maioria das pessoas t\u00eam receio de perdas provocadas por a\u00e7\u00f5es que utilizam a intelig\u00eancia artificial<br \/>\nCom o tema j\u00e1 incorporado ao repert\u00f3rio dos brasileiros, a intelig\u00eancia artificial tem provocado vis\u00f5es com sentimentos diversos entre a popula\u00e7\u00e3o. Uma das maiores inquieta\u00e7\u00f5es com o uso da tecnologia na regi\u00e3o Nordeste s\u00e3o as fraudes, golpes e v\u00eddeos falsos: 88% acham esse tipo de pr\u00e1tica muito preocupante, superando a percep\u00e7\u00e3o de IA em deepfakes influenciando elei\u00e7\u00f5es (79%) e tamb\u00e9m acima de outra consequ\u00eancia indesejada, o impacto ambiental dos datacenters (57%).<br \/>\nOs dados in\u00e9ditos s\u00e3o da 19\u00aa edi\u00e7\u00e3o da Pesquisa Observat\u00f3rio Febraban, realizada pelo IPESPE, no in\u00edcio de junho, nas cinco regi\u00f5es do pa\u00eds. O objetivo do levantamento foi trazer um panorama abrangente sobre o grau de conhecimento e familiaridade dos brasileiros com a intelig\u00eancia artificial.<br \/>\nNo recorte referente ao Nordeste, 90% das pessoas disseram j\u00e1 ter ouvido falar de IA, em um n\u00edvel pouco abaixo da m\u00e9dia nacional (92%); os que afirmaram conhecer bem a ferramenta na regi\u00e3o somam 35%, enquanto 68% relatam que j\u00e1 tiveram com certeza algum contato com a tecnologia. Os que disseram j\u00e1 ter utilizado a IA chegam a 52%. Os que n\u00e3o a utilizam alegam principalmente o medo de errar ou receber not\u00edcias falsas (30%) ou a preocupa\u00e7\u00e3o com a privacidade ou uso de dados (18%).<br \/>\nEntre os principais usos mencionados, o campe\u00e3o \u00e9 a busca de informa\u00e7\u00f5es e esclarecimento de d\u00favidas (57%), seguida de longe pela aplica\u00e7\u00e3o profissional (12%) e ajuda nos estudos, cursos ou aprendizado (10%). A principal vantagem esperada com a IA \u00e9 o ganho de tempo (42%), seguido do aprendizado de coisas novas (26%).<br \/>\nDiante de todas essas possibilidades, a intelig\u00eancia artificial \u00e9 recebida hoje mais com preocupa\u00e7\u00e3o (27%) do que com entusiasmo (24%).<br \/>\n\u201cA pesquisa traz um cen\u00e1rio compat\u00edvel com o est\u00e1gio atual do debate no pa\u00eds. Ainda estamos discutindo um marco legal espec\u00edfico para a intelig\u00eancia artificial, e \u00f3rg\u00e3os como a ANPD, a Autoridade Nacional de Prote\u00e7\u00e3o de Dados, v\u00eam testando instrumentos regulat\u00f3rios voltados \u00e0 IA e \u00e0 prote\u00e7\u00e3o de dados\u201d, ressalta o soci\u00f3logo e cientista pol\u00edtico Antonio Lavareda, presidente do Conselho Cient\u00edfico\u00a0do\u00a0IPESPE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa Observat\u00f3rio Febraban mostra que maioria das pessoas t\u00eam receio de perdas provocadas por a\u00e7\u00f5es&#8230;<\/p>\n","protected":false},"author":7,"featured_media":39188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-39187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg",300,223,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/07\/artigo.jpg","jetpack-related-posts":[{"id":32341,"url":"https:\/\/correiodasemana.com\/site\/cheque-representa-05-das-operacoes-financeiras-de-pagamento-no-pais\/","url_meta":{"origin":39187,"position":0},"title":"Cheque representa 0,5% das opera\u00e7\u00f5es financeiras de pagamento no pa\u00eds","author":"adminredacao","date":"Janeiro 27, 2025","format":false,"excerpt":"Segundo a Febraban, n\u00e3o h\u00e1 previs\u00e3o do fim do m\u00e9todo Ag\u00eancia Brasil O uso de cheques representa atualmente 0,5% das formas de pagamento pela popula\u00e7\u00e3o, mas n\u00e3o h\u00e1 previs\u00e3o sobre seu fim. Segundo a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban), o uso de cheques caiu 18% no ano passado, num acumulado\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/cheque_0.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/cheque_0.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/cheque_0.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/cheque_0.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/cheque_0.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28502,"url":"https:\/\/correiodasemana.com\/site\/exposicao-sertao-contemporaneo-de-wescley-braga\/","url_meta":{"origin":39187,"position":1},"title":"Exposi\u00e7\u00e3o Sert\u00e3o Contempor\u00e2neo de Wescley Braga","author":"adminredacao","date":"Fevereiro 27, 2024","format":false,"excerpt":"A Galeria do Sesc de Sobral tem o prazer de apresentar a exposi\u00e7\u00e3o \u201cSert\u00e3o Contempor\u00e2neo\u201d, do renomado artista cearense Wescley Braga. A mostra, que \u00e9 resultado de experimenta\u00e7\u00f5es fotogr\u00e1ficas, interfer\u00eancias digitais e intelig\u00eancia artificial, traz uma nova perspectiva sobre a paisagem e os elementos do sert\u00e3o cearense. A exposi\u00e7\u00e3o ter\u00e1\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/exposicao-sertao-Contemporaneo-Wescley-Braga-21.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/exposicao-sertao-Contemporaneo-Wescley-Braga-21.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/exposicao-sertao-Contemporaneo-Wescley-Braga-21.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/exposicao-sertao-Contemporaneo-Wescley-Braga-21.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":32190,"url":"https:\/\/correiodasemana.com\/site\/a-regulamentacao-da-inteligencia-artificial-no-brasil\/","url_meta":{"origin":39187,"position":2},"title":"A regulamenta\u00e7\u00e3o da Intelig\u00eancia Artificial no Brasil","author":"adminredacao","date":"Janeiro 16, 2025","format":false,"excerpt":"Por Wilson Pedroso* Os rob\u00f4s, com as mais variadas fun\u00e7\u00f5es, j\u00e1 est\u00e3o presentes em nossa vida cotidiana e a tend\u00eancia \u00e9 que o uso deles se intensifique cada vez mais. Mas como garantir que a tecnologia n\u00e3o ultrapasse os limites do que \u00e9 moral no que se refere aos direitos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/dfd0f08c-af3d-4fb4-8808-3db2f2a7ccd1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/dfd0f08c-af3d-4fb4-8808-3db2f2a7ccd1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/dfd0f08c-af3d-4fb4-8808-3db2f2a7ccd1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/dfd0f08c-af3d-4fb4-8808-3db2f2a7ccd1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35743,"url":"https:\/\/correiodasemana.com\/site\/inteligencia-artificial-ameaca-aprendizado-da-escrita-alerta-autor\/","url_meta":{"origin":39187,"position":3},"title":"Intelig\u00eancia artificial amea\u00e7a aprendizado da escrita, alerta autor","author":"adminredacao","date":"Setembro 29, 2025","format":false,"excerpt":"Para ele, perda da pr\u00e1tica pode resultar em retrocesso imensur\u00e1vel POR Luiz Claudio Ferreira - Rep\u00f3rter da Ag\u00eancia Brasil Um romance, a reda\u00e7\u00e3o de escola, uma poesia,\u00a0uma carta de amor, um aviso simples deixado na porta da geladeira. Estariam todos esses textos amea\u00e7ados pelas ferramentas de intelig\u00eancia artificial (IA)? Na\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Jornal-Correio-da-Semana-No-1090.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Jornal-Correio-da-Semana-No-1090.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Jornal-Correio-da-Semana-No-1090.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":29899,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-233\/","url_meta":{"origin":39187,"position":4},"title":"Em Tempo","author":"adminredacao","date":"Julho 8, 2024","format":false,"excerpt":"Confer\u00eancia Intelig\u00eancia Artificial A Universidade Estadual Vale do Acara\u00fa (UVA) foi sede da I Confer\u00eancia Intelig\u00eancia Artificial, Sindicatos e Luta por Direitos, realizada no dia 27 de junho, no campus Bet\u00e2nia, em Sobral. A programa\u00e7\u00e3o teve in\u00edcio com apresenta\u00e7\u00e3o musical do grupo Prata da Casa. Estudantes e professores de universidades\u2026","rel":"","context":"In &quot;Em Tempo&quot;","block_context":{"text":"Em Tempo","link":"https:\/\/correiodasemana.com\/site\/category\/em-tempo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/GILBERTO-GIL.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/GILBERTO-GIL.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/GILBERTO-GIL.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/GILBERTO-GIL.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/GILBERTO-GIL.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23766,"url":"https:\/\/correiodasemana.com\/site\/brasileiros-recebem-premio-da-nasa-por-projeto-de-inteligencia-artificial\/","url_meta":{"origin":39187,"position":5},"title":"Brasileiros recebem pr\u00eamio da Nasa por projeto de Intelig\u00eancia Artificial","author":"","date":"Abril 4, 2023","format":false,"excerpt":"Grupo desenvolveu sistema baseado em intelig\u00eancia artificial para identificar vazamentos de \u00f3leo nos oceanos. De acordo com um dos criadores, inten\u00e7\u00e3o \u00e9 buscar apoio governamental para implantar a plataforma. Na mitologia grega, Poseidon \u00e9 o deus que protege as \u00e1guas. E foi este o nome escolhido por um grupo de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/65179155-1005.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/65179155-1005.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/65179155-1005.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/65179155-1005.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/65179155-1005.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=39187"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39187\/revisions"}],"predecessor-version":[{"id":39189,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39187\/revisions\/39189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/39188"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=39187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=39187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=39187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}