{"id":39192,"date":"2026-07-14T18:50:40","date_gmt":"2026-07-14T21:50:40","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=39192"},"modified":"2026-07-14T18:50:40","modified_gmt":"2026-07-14T21:50:40","slug":"sobral-253-anos","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-253-anos\/","title":{"rendered":"Sobral, 253 anos"},"content":{"rendered":"<p>Seria injusti\u00e7a com benfeitores sobralenses e com a pr\u00f3pria hist\u00f3ria negar que Sobral tem crescido a passos largos nos \u00faltimos anos em todas as \u00e1reas, especialmente na educa\u00e7\u00e3o. Conforme IBGE\/2025, a popula\u00e7\u00e3o atingiu 216.519 habitantes distribu\u00eddos numa \u00e1rea territorial de 2.122 km2.. Todos merecemos mais que festa. Exigimos mais aten\u00e7\u00e3o e respeito!<br \/>\nLamentavelmente Sobral n\u00e3o vive clima prop\u00edcio para festa, mas, sim, para reflex\u00e3o e tomada de atitudes en\u00e9rgicas, dada a onda de viol\u00eancia e outros desmandos que j\u00e1 ganharam at\u00e9 repercuss\u00e3o nacional. \u00a0Segundo as autoridades, as provid\u00eancias est\u00e3o sendo adotadas. S\u00f3 que a popula\u00e7\u00e3o ainda n\u00e3o confirma resultado positivo e permanece sob amea\u00e7as de malfeitores ou deles sendo v\u00edtimas. Al\u00e9m disso, com as devidas exce\u00e7\u00f5es, \u00e9 flagrante a insensibilidade e o desd\u00e9m dos que comp\u00f5em os poderes constitu\u00eddos.<br \/>\nA lentid\u00e3o de a\u00e7\u00f5es, que deveriam ser proativas, demonstra car\u00e1ter apenas corretivo, quando n\u00e3o se convertem simples paliativos. Sem d\u00favida, isso deixa transparecer que tais autoridades consideram que o povo que aqui vive, ou que apenas aqui trabalha, flutua feliz e despreocupado num mar de paz e tranquilidade. Mesmo assim, amanh\u00e3 (05\/07), debaixo de festa, ser\u00e3o comemorados os 253 anos de emancipa\u00e7\u00e3o pol\u00edtica do munic\u00edpio.<br \/>\nNota-se, tamb\u00e9m, enorme lentid\u00e3o no processo de conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o e das autoridades, no intuito de estimular o povo a inteirar-se mais da sua pr\u00f3pria hist\u00f3ria. Esse \u00e9 o caminho atrav\u00e9s do qual se pode tomar conhecimento do passado para entender melhor o presente, a fim de projetar melhor ainda o futuro. E mais: \u00e9 a melhor forma de fazer-se respeitar, j\u00e1 que municia o cidad\u00e3o de subs\u00eddios para rebater cr\u00edticas; \u00e9 a melhor maneira de divulgar mais a verdade, desmistificar inverdades, enfim, \u00e9 a \u00fanica forma de se adquirir embasamento para argumentar ou contra-argumentar em qualquer situa\u00e7\u00e3o.<br \/>\nO lament\u00e1vel \u00e9 se observar ainda persistir por parte da maioria de pais e educadores uma grande d\u00edvida para com as crian\u00e7as e jovens, quanto ao ensino da hist\u00f3ria do seu torr\u00e3o natal. \u00c9 falha nacional, pois o mesmo ocorre em quase todos os munic\u00edpios brasileiros. Por isso, insisto em dizer que ainda adormece o interesse pela implanta\u00e7\u00e3o de disciplina espec\u00edfica sobre a hist\u00f3ria de cada munic\u00edpio. Sen\u00e3o vejamos: A garotada de hoje desvenda os pa\u00edses e at\u00e9 as gal\u00e1xias (Isso \u00e9 bom!), mas pouco ou nada sabe sobre a cidade em que vive (Isso \u00e9 mau, muito mau!).<br \/>\nDiante disso, como culpar as crian\u00e7as e os jovens se o desinteresse ou a ignor\u00e2ncia parte exatamente de quem poderia e deveria mudar essa triste realidade?<br \/>\nSugiro ent\u00e3o, que cada adultos fa\u00e7a seu mea-culpa e tente fazer algo para inverter o quadro. N\u00e3o s\u00f3 n\u00f3s sobralenses, mas voc\u00ea que mora noutra cidade tamb\u00e9m tente mudar essa realidade, fazendo com que essa nova gera\u00e7\u00e3o conhe\u00e7a mais a hist\u00f3ria do seu munic\u00edpio.<br \/>\nAl\u00e9m disso, tor\u00e7o para que a data tamb\u00e9m se reverta em ocasi\u00e3o para seu povo inteirar-se mais, questionar mais e exigir mais as provid\u00eancias cab\u00edveis e necess\u00e1rias, o que culminar\u00e1 em a\u00e7\u00f5es que tornem Sobral uma cidade melhor e seus moradores mais felizes. Para tanto, faz-se urgente exigir mais educa\u00e7\u00e3o mais seguran\u00e7a, mais sa\u00fade e mais oportunidade de trabalho, a fim de que todos possam trilhar os caminhos do bem.<br \/>\nComo pai e tamb\u00e9m educador, levando-se em conta que comunicador tamb\u00e9m tem como fun\u00e7\u00e3o informar e educar, tento aqui solver parte dessa d\u00edvida. Portanto, conhe\u00e7a um pouco mais da hist\u00f3ria da Fazenda Cai\u00e7ara, passando pela Vila Distinta e Real at\u00e9 a atual cidade de Sobral. Parab\u00e9ns, Sobral!<\/p>\n<p>*************<\/p>\n<p>POR QUE CAI\u00c7ARA?<br \/>\nNome dado \u00e0 por\u00e7\u00e3o de terra herdada por Quit\u00e9ria Maria de Jesus, como dote de seu casamento com Ant\u00f4nio Rodrigues de Magalh\u00e3es. Quit\u00e9ria havia herdado de sua m\u00e3e, Apol\u00f4nia da Costa, casada com o sargento-mor Ant\u00f4nio Marques de Leit\u00e3o. E Apol\u00f4nia, por sua vez, teve sua parte herdada de seu pai Ant\u00f4nio da Costa Peixoto, portugu\u00eas, vereador em Aquiraz. A 14 de outubro de 1702, este edil conseguiu uma sesmaria \u00e0s margens do rio Acara\u00fa, medindo uma l\u00e9gua e meia de comprimento com meia l\u00e9gua de largura, indo da margem esquerda do rio Acara\u00fa ao sop\u00e9 da serra da Meruoca.\u00a0 De suas terras, Ant\u00f4nio e Quit\u00e9ria fundaram a fazenda \u00e0 qual deram o nome de Cai\u00e7ara pelo fato de ter sido no in\u00edcio protegida com uma cerca de varas. Isso \u00e9 corroborado pela etimologia: a palavra Cai\u00e7ara vem do tupi e significa \u201ccerca feita de mato\u201d.<br \/>\nProtesto\u00a0&#8211; Muitos que levam adiante a hist\u00f3ria de Sobral em seus escritos ou pronunciamentos t\u00eam pecado por omitir a grande import\u00e2ncia do padre visitador Lino Correia Gomes. Para mim, ele foi o verdadeiro fundador de Sobral e n\u00e3o o fazendeiro Ant\u00f4nio Rodrigues de Magalh\u00e3es. E explico: Pe. Lino foi o pai da ideia de instalar a sede de um curato por aqui. Com o curato, veio o desenvolvimento. Ant\u00f4nio simplesmente doou terras e n\u00e3o tinha a m\u00ednima inten\u00e7\u00e3o de fundar uma cidade, inclusive pouco permanecia nesta regi\u00e3o.<\/p>\n<p>POR QUE VILA DISTINTA E REAL DE SOBRAL?<br \/>\nA 14 de novembro de 1772, por ordem do Governador e Comandante Geral de Pernambuco, Manuel da Cunha de Menezes, foi criada a Vila Distinta e Real de Sobral. Sua instala\u00e7\u00e3o oficial, bem como a elei\u00e7\u00e3o e posse da primeira C\u00e2mara de Vereadores s\u00f3 aconteceu no dia 5 de julho de 1773. O nome Vila Distinta e Real de Sobral traz consigo certo ar de nobreza. Sen\u00e3o vejamos:<br \/>\nDISTINTA\u00a0&#8211; Porque n\u00e3o tivera origem ind\u00edgena ou b\u00e1rbara, nem fora sede de miss\u00f5es jesu\u00edticas ou de outras congrega\u00e7\u00f5es religiosas. Sobral fora colonizada por portugueses ou descendentes destes e catequizada por padres seculares.\u00a0 Todas as vilas surgidas dessa forma, de coloniza\u00e7\u00e3o totalmente branca, eram consideradas com ares de nobreza e, portanto, distintas.<br \/>\nREAL\u00a0&#8211; Pelo fato de ter sido criada por ordem direta do Rei e, por isso, recebia dele prote\u00e7\u00e3o e simpatia. Existiam vilas criadas de aldeias ind\u00edgenas, mas n\u00e3o recebiam os adjetivos \u201cDistinta e Real\u201d.\u00a0 Eram chamadas apenas Vila ou Vila Nova, acrescido do nome do local. Vila formada de habitantes estritamente de origem portuguesas era Distinta e Real, como foi o caso de Sobral, exemplo \u00fanico no Cear\u00e1. Quando foi baixado o decreto pelo Rei para cria\u00e7\u00e3o das Vilas era uma ordem retirar todos os nomes ind\u00edgenas e alterar para nomes de locais j\u00e1 existentes em Portugal.<br \/>\nNo caso deste munic\u00edpio, a denomina\u00e7\u00e3o vem do nome da terra dos\u00a0ancestrais de Quit\u00e9ria Maria de Jesus, esposa de Ant\u00f4nio Rodrigues de Magalh\u00e3es.\u00a0Em Portugal pode-se encontrar mais de uma dezena de localidades que recebem o nome Sobral acrescido de mais algum designativo.<br \/>\nSOBRAL\u00a0&#8211; Sobral (ou sobreiral) \u00e9 o coletivo da palavra sobro, sovro ou sobreiro (fotos). Trata-se da denomina\u00e7\u00e3o popular de\u00a0Quercus S\u00faber, uma\u00a0das \u00e1rvores florestais mais abundantes em Portugal.\u00a0\u00c9 a \u00fanica querc\u00ednea produtora de corti\u00e7a da regi\u00e3o mediterr\u00e2nea.<\/p>\n<p>POR QUE FIDEL\u00cdSSIMA CIDADE JANU\u00c1RIA DO ACARA\u00da?<br \/>\nVale lembrar que o munic\u00edpio j\u00e1 recebeu o nome de Janu\u00e1ria. Quando da eleva\u00e7\u00e3o de Vila \u00e0 categoria de cidade, o presidente da Prov\u00edncia do Cear\u00e1 (hoje equivalente a governador do Estado), Jos\u00e9 Martiniano de Alencar, que era padre e pai do famoso romancista cearense Jos\u00e9 de Alencar, atrav\u00e9s da Lei n\u00ba 229, de 12 de janeiro de 1841, deu o nome a esta terra de Fidel\u00edssima Cidade Janu\u00e1ria do Acara\u00fa.<br \/>\nFIDEL\u00cdSSIMA\u00a0&#8211; Pela fidelidade dos sobralenses ao Pe. Alencar, quando da revolta contra o seu governo ocorrida na ent\u00e3o Vila Distinta e Real de Sobral em 1840. Houve s\u00e9rios conflitos com v\u00e1rias mortes, saindo vitorioso o Pe. Alencar.<br \/>\nJANU\u00c1RIA\u00a0&#8211; Homenagem que o presidente da Prov\u00edncia queria prestar \u00e0 jovem irm\u00e3 do imperador D. Pedro II, a Princesa\u00a0Janu\u00e1ria, de 19 anos (Da\u00ed,\u00a0 \u201cPrincesa do Norte\u201d). A popula\u00e7\u00e3o n\u00e3o gostou nem pouco da mudan\u00e7a de Sobral para Janu\u00e1ria. No ano seguinte, o novo presidente, Jos\u00e9 Joaquim Coelho, atrav\u00e9s da Lei n\u00ba 244, de 25 de outubro de 1842, atender aos reclamos da popula\u00e7\u00e3o retornando o nome do lugar para Sobral. Como Janu\u00e1ria, Sobral ainda permaneceu durante um ano, nove meses e treze dias.<\/p>\n<p><em><strong>DOMINGO NA EDUCADORA FM 107,5 &#8211; SOBRAL-CE \u00c1UDIO: https:\/\/www.radios.com.br\/play\/12869 \u00c1UDIOV\u00cdDEO: https:\/\/www.facebook.com\/educadoradonordestefm NO YOUTUBE: R\u00e1dio Educadora FM 107.5 Neste domingo (5), das 10h30 \u00e0s 12h30, PROGRAMA ARTEM\u00cdSIO DA COSTA com not\u00edcias, reportagens, curiosidades, m\u00fasica de boa qualidade. DESTAQUE: \u201cSOBRAL &#8211; 253 ANOS DE PROGRESSO\u201d. Participe 3611-1550 \/\/ 3611-2496 \/\/ Face book: Artem\u00edsio da Costa. UM DOMINGO ABEN\u00c7OADO E DIVERTIDO!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seria injusti\u00e7a com benfeitores sobralenses e com a pr\u00f3pria hist\u00f3ria negar que Sobral tem crescido&#8230;<\/p>\n","protected":false},"author":7,"featured_media":24516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,82],"tags":[],"class_list":["post-39192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-poucas-e-boas"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2-300x300.jpg",300,300,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg",400,400,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2-400x340.jpg",400,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/poucas-e-boas\/\" rel=\"category tag\">Poucas e Boas<\/a>","tag_info":"Poucas e Boas","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg","jetpack-related-posts":[{"id":20181,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-89\/","url_meta":{"origin":39192,"position":0},"title":"Becco ponto Com","author":"","date":"Junho 19, 2022","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. Do abandono do Becco do Cotovelo. 02. Do golpe dos politicos nos eleitores. 03. De um capit\u00e3o l\u00e1 e outro c\u00e1 em 2023. 04. Dos pastores ca\u00e7adores de votos, ui! 05. Das quadrilhas de pol\u00edticos este ano. 06. Do ensino paga e passa t\u00e3o fabricado. 07. Das\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18442,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-91\/","url_meta":{"origin":39192,"position":1},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Dezembro 27, 2021","format":false,"excerpt":"Prefeito Ivo Gomes esteve entregando a popula\u00e7\u00e3o do Bairro do Junco, a quadra esportiva, Jo\u00e3o Coelho, sendo esse mais um espa\u00e7o para a pr\u00e1tica esportiva para os jovens residentes no Bairro. O gestor municipal tamb\u00e9m deu um trato aos arredores da quadra esportiva, sendo mais uma \u00e1rea de lazer para\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":37485,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-249\/","url_meta":{"origin":39192,"position":2},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Fevereiro 20, 2026","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Da performance do \u201cBloco dos Sujos\u201d, ufa! Das m\u00e1scaras pol\u00edticas caindo no carnaval sujo. Dos m\u00e9dicos novos batizando os seus clientes. Das faculdades produzindo semianalfabetos. Do fuxico dos velhos no Becco, os bunda moles. Do canto de carroceria no Cid, via Elmano PT. Dos chor\u00f5es no carnaval, os\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33997,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-216\/","url_meta":{"origin":39192,"position":3},"title":"Becco ponto Com","author":"adminredacao","date":"Junho 4, 2025","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Dos importantes pol\u00edticos de cidades pequenas na pista, ufa! Dos bab\u00f5es antigos na onda da chupeta chorando pitangas. Das faculdades formando futuros motoristas de Uber, ufa! Das dondocas novas ricas bofando nos gabinetes de beleza. Da pol\u00edtica \u201cme engana que eu gosto\u201d Ciro x Cid, com briguinhas. Da\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28470,"url":"https:\/\/correiodasemana.com\/site\/educacao-e-cidadania-37\/","url_meta":{"origin":39192,"position":4},"title":"EDUCA\u00c7\u00c3O E CIDADANIA \u2022","author":"adminredacao","date":"Fevereiro 27, 2024","format":false,"excerpt":"Os Carnavais no Brasil O Carnaval\u00a0foi trazido para o Brasil pelos colonizadores portugueses.\u00a0Os historiadores afirmam que a festividade estabeleceu-se no pa\u00eds entre os s\u00e9culos XVI e XVII\u00a0e teve como primeira pr\u00e1tica o Entrudo. Essa brincadeira fixou-se primeiramente no Rio de Janeiro e era realizada dias antes do in\u00edcio da Quaresma.\u00a0(mundoeducacao.uol.com.br).\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":31936,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-197\/","url_meta":{"origin":39192,"position":5},"title":"Becco ponto Com","author":"adminredacao","date":"Dezembro 24, 2024","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Dos fatos e boatos nas emissoras sobre a pol\u00edtica t\u00e3o nossa. Dos bab\u00f5es contumazes na porta do novo poder. Ufa, Sobral! De uma oposi\u00e7\u00e3o odienta e incapaz puxada as coisas petistas. Dos pol\u00edticos poderosos que n\u00e3o aceitam perder o osso, ufa! Da ruma de bancos de emprestar dinheiro\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=39192"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39192\/revisions"}],"predecessor-version":[{"id":39193,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39192\/revisions\/39193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/24516"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=39192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=39192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=39192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}