{"id":39235,"date":"2026-07-14T19:08:18","date_gmt":"2026-07-14T22:08:18","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=39235"},"modified":"2026-07-14T19:08:18","modified_gmt":"2026-07-14T22:08:18","slug":"comunidade-de-alianca-filhos-de-siao","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/comunidade-de-alianca-filhos-de-siao\/","title":{"rendered":"Comunidade de Alian\u00e7a Filhos de Si\u00e3o"},"content":{"rendered":"<p>Um dos mitos sobre a Comunidade de Alian\u00e7a \u00e9 pensar que seus membros vivem uma voca\u00e7\u00e3o mais leve ou menos exigente. Na verdade, fomos chamados a encarnar, testemunhar e frutificar o Carisma. Esses tr\u00eas verbos expressam profundamente a nossa identidade e miss\u00e3o.<br \/>\nPor estarmos inseridos no meio secular, somos chamados a ser Filhos de Si\u00e3o onde quer que estejamos. Nossa pr\u00f3pria defini\u00e7\u00e3o vocacional nos apresenta a necessidade de uma vida profunda de ora\u00e7\u00e3o, fraternidade e apostolado.<br \/>\nEm nossa rotina, devemos dar primazia \u00e0 vida de ora\u00e7\u00e3o, sem negligenciar as orienta\u00e7\u00f5es recebidas da Comunidade. Este caminho \u00e9 marcado por ren\u00fancias, mas tamb\u00e9m por abundantes b\u00ean\u00e7\u00e3os.<br \/>\nToda ter\u00e7a e quarta-feira nos reunimos na Comunidade para as c\u00e9lulas, momentos em que somos formados, partilhamos nossa vida e rezamos juntos. Essa viv\u00eancia nos acompanhar\u00e1 por toda a vida.<br \/>\nNossa rotina deve ser continuamente moldada pelo chamado de Deus. A viv\u00eancia da pobreza consiste, antes de tudo, em n\u00e3o negar a Deus o nosso tempo. Al\u00e9m disso, realizamos nossa Koinonia, devolvemos o d\u00edzimo e permanecemos atentos \u00e0s necessidades da Comunidade de Vida, partilhando nossos bens com os irm\u00e3os.<br \/>\nTamb\u00e9m praticamos o despojamento duas vezes ao ano, durante o Advento e a Quaresma, retirando e doando aquilo que est\u00e1 em excesso ou em desuso em nossa vida.<br \/>\nNossa viv\u00eancia da obedi\u00eancia passa pela submiss\u00e3o ao formador comunit\u00e1rio, a quem devemos recorrer quando necessitamos de dispensa e com quem partilhamos nossa caminhada comunit\u00e1ria. Al\u00e9m dele, somos chamados a obedecer \u00e0s autoridades constitu\u00eddas pela Comunidade: a fundadora, o cofundador, o formador pessoal, o coordenador das miss\u00f5es, os coordenadores de minist\u00e9rio e demais respons\u00e1veis designados pela Comunidade.<br \/>\nO namoro na Comunidade de Alian\u00e7a pode acontecer tanto durante as etapas vocacionais quanto ap\u00f3s a consagra\u00e7\u00e3o. Esse relacionamento pode ser vivido com pessoas de dentro ou de fora da Comunidade, desde que seja fruto de um processo de conversa, discernimento e acompanhamento com o formador pessoal, normalmente por um per\u00edodo m\u00ednimo de tr\u00eas meses.<br \/>\nNo que se refere \u00e0 castidade, a Comunidade de Alian\u00e7a, assim como a Comunidade de Vida, \u00e9 chamada a viver a sobriedade no vestir, no falar e no comportamento, dentro e fora da Comunidade.<br \/>\nNo apostolado, estamos inseridos em todo o corpo comunit\u00e1rio, servindo por meio dos nossos dons e talentos, mas tamb\u00e9m atrav\u00e9s da disponibilidade e da oferta de vida. Crescemos como fam\u00edlia e encontramos alegria na entrega que fazemos a Deus, \u00e0 Igreja e \u00e0 Comunidade.<br \/>\nNossa oferta tamb\u00e9m \u00e9 total. Entregamos nosso tempo livre, nosso descanso e aquilo que poder\u00edamos reservar para n\u00f3s mesmos, escolhendo Deus em primeiro lugar.<br \/>\nO mundo muitas vezes n\u00e3o compreende a nossa escolha de vida. Por isso, convivendo em meio \u00e0 sociedade, somos chamados a dar testemunho de fidelidade e amor \u00e0 nossa voca\u00e7\u00e3o. Precisamos ser luz dentro e fora da Comunidade.<br \/>\nEsta \u00e9 a nossa identidade: estar no mundo sem pertencer ao mundo. \u00c9 viver o extraordin\u00e1rio de Deus no ordin\u00e1rio da nossa vida.<br \/>\nPedro Allef Silva Vasconcelos<br \/>\nConsagrado com Promessas Definitivas na Comunidade de Alian\u00e7a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos mitos sobre a Comunidade de Alian\u00e7a \u00e9 pensar que seus membros vivem uma&#8230;<\/p>\n","protected":false},"author":7,"featured_media":12821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-39235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg",2560,1718,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-300x201.jpg",300,201,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-768x516.jpg",640,430,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-1024x687.jpg",640,429,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-1536x1031.jpg",1536,1031,true],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-2048x1375.jpg",2048,1375,true],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-1024x687.jpg",1024,687,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-720x380.jpg",540,285,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg","jetpack-related-posts":[{"id":37379,"url":"https:\/\/correiodasemana.com\/site\/comunidade-filhos-de-siao-17\/","url_meta":{"origin":39235,"position":0},"title":"COMUNIDADE FILHOS DE SI\u00c3O","author":"adminredacao","date":"Fevereiro 20, 2026","format":false,"excerpt":"Trip\u00e9 da Voca\u00e7\u00e3o Filhos de Si\u00e3o Ora\u00e7\u00e3o Contemplativa O primeiro presente \u00e9 a Ora\u00e7\u00e3o Contemplativa. Orar n\u00e3o \u00e9 apenas cumprir um dever, nem rezar por simples repeti\u00e7\u00e3o de palavras. O que o Senhor nos pede \u00e9 a contempla\u00e7\u00e3o: um encontro mais profundo, cuidadoso e demorado, vivido com zelo e amor.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":20714,"url":"https:\/\/correiodasemana.com\/site\/retiro-da-juventude-filhos-de-siao-eu1\/","url_meta":{"origin":39235,"position":1},"title":"Retiro da Juventude Filhos de Si\u00e3o: Eu+1","author":"","date":"Agosto 14, 2022","format":false,"excerpt":"O Retiro da Juventude Filhos de Si\u00e3o Eu+1 nasceu em 2003 no seio da Comunidade Filhos de Si\u00e3o com o objetivo de oportunizar aos jovens um encontro pessoal com Jesus. H\u00e1 alguns anos vem ocorrendo no m\u00eas de julho por ser f\u00e9rias e os jovens estarem mais livres e disposto\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":34905,"url":"https:\/\/correiodasemana.com\/site\/comunidade-filhos-de-siao-celebra-27-anos-de-missao-com-consagracao-definitiva-de-nove-mulheres\/","url_meta":{"origin":39235,"position":2},"title":"Comunidade Filhos de Si\u00e3o celebra 27 anos de miss\u00e3o com consagra\u00e7\u00e3o definitiva de nove mulheres","author":"adminredacao","date":"Agosto 4, 2025","format":false,"excerpt":"Em Marco, Dom Vasconcelos presidiu, na noite da \u00faltima segunda-feira (28), a Missa em A\u00e7\u00e3o de Gra\u00e7as pelos 27 anos da Comunidade Cat\u00f3lica Filhos de Si\u00e3o, na capela da sede da comunidade. Durante a celebra\u00e7\u00e3o, nove mulheres realizaram sua consagra\u00e7\u00e3o definitiva na comunidade de Alian\u00e7a. A Santa Missa reuniu familiares,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33600,"url":"https:\/\/correiodasemana.com\/site\/comunidade-filhos-de-siao-13\/","url_meta":{"origin":39235,"position":3},"title":"COMUNIDADE  FILHOS DE SI\u00c3O","author":"adminredacao","date":"Maio 5, 2025","format":false,"excerpt":"Por que devo responder \u201cSim\u201d ao chamado do Carisma? Em certo sentido, o relacionamento com Deus. Partindo da realidade do amor de Deus pelo homem, amor pessoal e individualizado, como est\u00e1 escrito em nosso estatuto \u201c Nossa ess\u00eancia \u00e9 o AMOR! \u201cAMAR O AMOR QUE N\u00c3O \u00c9 AMADO\u201d nos emerge\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33568,"url":"https:\/\/correiodasemana.com\/site\/comunidade-filhos-de-siao-celebra-renovacao-das-promessas-e-acolhimento-de-novos-membros\/","url_meta":{"origin":39235,"position":4},"title":"Comunidade Filhos de Si\u00e3o celebra Renova\u00e7\u00e3o das Promessas e acolhimento de novos membros","author":"adminredacao","date":"Abril 29, 2025","format":false,"excerpt":"A Comunidade Cat\u00f3lica Filhos de Si\u00e3o celebrou, de 23 a 26 de abril, a Renova\u00e7\u00e3o das Promessas da Comunidade de Vida e Alian\u00e7a, a consagra\u00e7\u00e3o de novos membros, bem como o acolhimento de disc\u00edpulos e postulantes nas miss\u00f5es de Marco, Acara\u00fa, Bela Cruz e Itarema. Com a celebra\u00e7\u00e3o da Santa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Jornal-Correio-da-Semana-No-1069.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Jornal-Correio-da-Semana-No-1069.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Jornal-Correio-da-Semana-No-1069.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":21228,"url":"https:\/\/correiodasemana.com\/site\/o-carisma-e-o-sentido-de-pertenca\/","url_meta":{"origin":39235,"position":5},"title":"O carisma e o sentido de perten\u00e7a","author":"","date":"Outubro 10, 2022","format":false,"excerpt":"A comunidade Filhos de Si\u00e3o \u00e9 formada pela comunidade de vida, comunidade de alian\u00e7a e grupos de ora\u00e7\u00e3o. Cada realidade \u00e9 um chamado de Deus e cada um tem sua beleza e seu valor. Sendo assim somos uma grande fam\u00edlia, a fam\u00edlia Filhos de Si\u00e3o! Cada um deve estar aonde\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Catedral-da-Se-N.-S.-da-Conceicao-Sobral-Ceara-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=39235"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39235\/revisions"}],"predecessor-version":[{"id":39236,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/39235\/revisions\/39236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12821"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=39235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=39235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=39235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}